{"id":10519,"date":"2013-10-31T21:27:17","date_gmt":"2013-10-31T19:27:17","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=10519"},"modified":"2013-10-31T21:27:17","modified_gmt":"2013-10-31T19:27:17","slug":"inmovilidad-substancial","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2013\/10\/31\/inmovilidad-substancial\/","title":{"rendered":"INMOVILIDAD SUBSTANCIAL"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2013\/10\/Rafael-Moneo-Circo-stepienybarno-.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10520\" title=\"Rafael Moneo-Circo-stepienybarno\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2013\/10\/Rafael-Moneo-Circo-stepienybarno-.jpg\" alt=\"Rafael Moneo-Circo-stepienybarno\" width=\"350\" height=\"353\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2013\/10\/Rafael-Moneo-Circo-stepienybarno-.jpg 350w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2013\/10\/Rafael-Moneo-Circo-stepienybarno--178x180.jpg 178w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2013\/10\/Rafael-Moneo-Circo-stepienybarno--316x319.jpg 316w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p>Por Rafael Moneo desde Circo.<\/p>\n<p><!--more--><\/p>\n<p align=\"left\">\n<p>\u201c(\u2026) Ahora explicar\u00e9 brevemente c\u00f3mo funciona el edificio. Si quer\u00eda que se mantuviera la condici\u00f3n geogr\u00e1fica del lugar, necesitaba construir de un modo compacto, estricto, preciso. Tan s\u00f3lo el auditorio y la sala de congresos se har\u00edan ver sobre las plataformas bajo las que se albergan los otros elementos del programa. Desde las plataformas, las gentes podr\u00e1n disfrutar de espl\u00e9ndidas vistas sobre el mar. No creo que m\u00e1s explicaciones sean necesarias. No fue el an\u00e1lisis del lugar lo que me llev\u00f3 a esta soluci\u00f3n, sino una visi\u00f3n m\u00e1s sint\u00e9tica y global del mismo. El proyecto de arquitectura ha nacido en este caso del lugar.<\/p>\n<p>El otro proyecto que me gustar\u00eda discutir, la Fundaci\u00f3n Pilar y Joan Mir\u00f3 en Palma de Mallorca, me permitir\u00e1 desarrollar m\u00e1s extensamente estas ideas. La nueva construcci\u00f3n se proyect\u00f3 para cumplir el testamento de Joan Mir\u00f3, quien quer\u00eda que Palma de Mallorca contara con una instituci\u00f3n que al par de contener su \u00faltima obra proporcionara a estudiosos y artistas la oportunidad de estudiar su trabajo. El edificio se levanta en un terreno propiedad de Mir\u00f3, que disfrutaba de espl\u00e9ndidas vistas sobre la Bah\u00eda de Palma cuando \u00e9l y su familia se instalaron en la ciudad a fines de los a\u00f1os 40. En la propiedad citada, producto de la mente y que como tal puede ser pensada, representada, descrita. Estoy incluso dispuesto a admitir el uso metaf\u00f3rico que de la palabra arquitectura continuamente se hace y, sin embargo, en mi opini\u00f3n la arquitectura trasciende dicho uso y alcanza su verdadero \u201cstatus\u201d cuando se realiza, cuando adquiere su ser en cuanto que objeto, cuando se convierte en la materialidad de lo construido y toma la forma de edificio. La arquitectura queda materialmente atrapada en la construcci\u00f3n y alcanza su aut\u00e9ntica consistencia gracias al uso de un lenguaje que fija su ser en lo que Borchers llamaba \u201cinmovilidad substancial\u201d.<\/p>\n<p align=\"left\">\n<p align=\"left\">Acceder a la informaci\u00f3n, <a href=\"http:\/\/www.mansilla-tunon.com\/circo\/epoca1\/pdf\/1995_024.pdf\">aqu\u00ed<\/a><\/p>\n<p align=\"left\">\n<p align=\"left\">\n<p align=\"left\">Noticia seleccionada por el Canal de arquitectura STEPIENYBARNO.<\/p>\n<p align=\"left\"><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\">STEPIENYBARNO EN LINKEDIN<\/a><\/p>\n<p align=\"left\"><a href=\"http:\/\/twitter.com\/stepienybarno\/stepienybarno\">STEPIENYBARNO EN TWITTER<\/a><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">STEPIENYBARNO EN FACEBOOK<\/a><\/p>\n<p align=\"left\">\n<p align=\"left\">*Stepienybarno est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p align=\"left\">Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n (comunicaci\u00f3n y difusi\u00f3n) y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p align=\"left\">A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a> y redactores de <a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\">LA CIUDAD VIVA<\/a>.<\/p>\n<p align=\"left\">\n<p align=\"left\">* Los editores de esta publicaci\u00f3n digital no nos hacemos cargo de de los comentarios y\u00a0 conceptos vertidos en los textos firmados por otras personas, siendo \u00e9stos de responsabilidad exclusiva de sus autores.<\/p>\n<p align=\"left\">\n<p align=\"left\">* Tu comentario podr\u00e1 ser moderado, por lo tanto, aunque aparezca inmediatamente al ser publicado en la entrada, los editores de esta publicaci\u00f3n digital nos reservamos el derecho tanto de editarlo (si fuera necesario, para hacerlo m\u00e1s legible) como de eliminarlo en el caso de que se usen expresiones incorrectas (descalificaciones, palabras malsonantes\u2026). A su vez, si quieres comentar desde el anonimato puedes hacerlo, aunque, nosotros personalmente, agradecemos que tod@s nos podamos identificar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Rafael Moneo desde Circo.<\/p>\n<p>(m\u00e1s&#8230;)<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[34,244],"tags":[4274,9,2661,336],"series":[],"class_list":["post-10519","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-canal-de-arquitectura","tag-actualidad","tag-arquitectura","tag-circo","tag-rafael-moneo"],"aioseo_notices":[],"episode_featured_image":false,"episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"mSrgUcs71E\"><a href=\"https:\/\/stepienybarno.es\/blog\/2013\/10\/31\/inmovilidad-substancial\/\">INMOVILIDAD SUBSTANCIAL<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2013\/10\/31\/inmovilidad-substancial\/embed\/#?secret=mSrgUcs71E\" width=\"500\" height=\"350\" title=\"\u00abINMOVILIDAD SUBSTANCIAL\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"mSrgUcs71E\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/10519"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=10519"}],"version-history":[{"count":2,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/10519\/revisions"}],"predecessor-version":[{"id":10522,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/10519\/revisions\/10522"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=10519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=10519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=10519"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=10519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}