{"id":11766,"date":"2013-12-23T11:15:53","date_gmt":"2013-12-23T09:15:53","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=11766"},"modified":"2013-12-23T11:15:53","modified_gmt":"2013-12-23T09:15:53","slug":"solo-hay-una-arquitectura-la-que-sirve-al-hombre","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2013\/12\/23\/solo-hay-una-arquitectura-la-que-sirve-al-hombre\/","title":{"rendered":"SOLO HAY UNA ARQUITECTURA: LA QUE SIRVE AL HOMBRE"},"content":{"rendered":"<p align=\"left\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2013\/12\/Vegaviana-_-Jos\u00e9-Luis-Fern\u00e1ndez-del-Amo-stepienybarno-2-.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11768\" title=\"Vegaviana _ Jos\u00e9 Luis Fern\u00e1ndez del Amo-stepienybarno 2\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2013\/12\/Vegaviana-_-Jos\u00e9-Luis-Fern\u00e1ndez-del-Amo-stepienybarno-2--350x238.jpg\" alt=\"Vegaviana _ Jos\u00e9 Luis Fern\u00e1ndez del Amo-stepienybarno 2\" width=\"350\" height=\"238\" \/><\/a><\/p>\n<blockquote>\n<p align=\"left\"><!--more--><\/p>\n<p align=\"left\">\u201cSolo hay una arquitectura: la que sirve al hombre. Pero tenemos el deber, la responsabilidad de hacer que ese hombre quiera vivir mejor. Que la arquitectura le asista en una aut\u00e9ntica superaci\u00f3n: la casa, el taller, la escuela, la iglesia, la ciudad. Desde fuera y por dentro, desde el urbanismo a la interioridad. Hacerle grato el entrar en la casa y el salir de ella. Quitar fronteras, chafar orgullos, reducir diferencias, que todo sea recinto de convivencia y el \u00e1mbito de su paz. Que la objetiva virtualidad del arte le llegue al espacio vital y al utensilio. Que se sienta bien y se haga mejor. Que le proteja de la intemperie y le alivie de las fuerzas oscuras que ensombrecen el mundo\u201d.<\/p>\n<p align=\"left\">Jos\u00e9 Luis Fern\u00e1ndez del Amo<\/p>\n<p align=\"left\">Visto en: <span style=\"text-decoration: underline;\"><a href=\"http:\/\/kcy.me\/wr7y\">http:\/\/kcy.me\/wr7y<\/a><\/span><\/p>\n<p align=\"left\"><span style=\"text-decoration: underline;\"><a style=\"text-align: center;\" href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2013\/12\/Jos\u00e9-Luis-Fern\u00e1ndez-del-Amo-stepienybarno-.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"Jos\u00e9 Luis Fern\u00e1ndez del Amo-stepienybarno\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2013\/12\/Jos\u00e9-Luis-Fern\u00e1ndez-del-Amo-stepienybarno-.jpg\" alt=\"Jos\u00e9 Luis Fern\u00e1ndez del Amo-stepienybarno\" width=\"200\" height=\"175\" \/><\/a><\/span><\/p>\n<p align=\"left\">\n<\/blockquote>\n<p align=\"left\">\n<p align=\"left\">Noticia seleccionada por el Canal de arquitectura STEPIENYBARNO.<\/p>\n<p align=\"left\"><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\">STEPIENYBARNO EN LINKEDIN<\/a><\/p>\n<p align=\"left\"><a href=\"http:\/\/twitter.com\/stepienybarno\/stepienybarno\">STEPIENYBARNO EN TWITTER<\/a><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">STEPIENYBARNO EN FACEBOOK<\/a><\/p>\n<p align=\"left\">\n<p align=\"left\">*Stepienybarno est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p align=\"left\">Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n (comunicaci\u00f3n y difusi\u00f3n) y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p align=\"left\">A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a> y redactores de <a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\">LA CIUDAD VIVA<\/a>.<\/p>\n<p align=\"left\">\n<p align=\"left\">* Los editores de esta publicaci\u00f3n digital no nos hacemos cargo de de los comentarios y\u00a0 conceptos vertidos en los textos firmados por otras personas, siendo \u00e9stos de responsabilidad exclusiva de sus autores.<\/p>\n<p align=\"left\">\n<p align=\"left\">* Tu comentario podr\u00e1 ser moderado, por lo tanto, aunque aparezca inmediatamente al ser publicado en la entrada, los editores de esta publicaci\u00f3n digital nos reservamos el derecho tanto de editarlo (si fuera necesario, para hacerlo m\u00e1s legible) como de eliminarlo en el caso de que se usen expresiones incorrectas (descalificaciones, palabras malsonantes\u2026). A su vez, si quieres comentar desde el anonimato puedes hacerlo, aunque, nosotros personalmente, agradecemos que tod@s nos podamos identificar.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[34,244],"tags":[4274,9,1516],"series":[],"class_list":["post-11766","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-canal-de-arquitectura","tag-actualidad","tag-arquitectura","tag-jose-luis-fernandez-del-amo"],"aioseo_notices":[],"episode_featured_image":false,"episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"FXjGH9aZz9\"><a href=\"https:\/\/stepienybarno.es\/blog\/2013\/12\/23\/solo-hay-una-arquitectura-la-que-sirve-al-hombre\/\">SOLO HAY UNA ARQUITECTURA: LA QUE SIRVE AL HOMBRE<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2013\/12\/23\/solo-hay-una-arquitectura-la-que-sirve-al-hombre\/embed\/#?secret=FXjGH9aZz9\" width=\"500\" height=\"350\" title=\"\u00abSOLO HAY UNA ARQUITECTURA: LA QUE SIRVE AL HOMBRE\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"FXjGH9aZz9\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/11766"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=11766"}],"version-history":[{"count":2,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/11766\/revisions"}],"predecessor-version":[{"id":11770,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/11766\/revisions\/11770"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=11766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=11766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=11766"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=11766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}