{"id":12199,"date":"2014-01-22T10:17:15","date_gmt":"2014-01-22T08:17:15","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=12199"},"modified":"2014-01-22T10:21:00","modified_gmt":"2014-01-22T08:21:00","slug":"jose-pico-hablando-de-emprendimiento","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2014\/01\/22\/jose-pico-hablando-de-emprendimiento\/","title":{"rendered":"JOS\u00c9 MANUEL PICO HABLANDO DE EMPRENDIMIENTO"},"content":{"rendered":"<p align=\"left\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2014\/01\/jose-pico-etudio-d3-emprendimiento-creatividad-lean_stepienybarno-.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12200\" title=\"jose-pico-etudio-d3-emprendimiento-creatividad-lean_stepienybarno\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2014\/01\/jose-pico-etudio-d3-emprendimiento-creatividad-lean_stepienybarno-.jpg\" alt=\"jose-pico-etudio-d3-emprendimiento-creatividad-lean_stepienybarno\" width=\"350\" height=\"213\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2014\/01\/jose-pico-etudio-d3-emprendimiento-creatividad-lean_stepienybarno-.jpg 350w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2014\/01\/jose-pico-etudio-d3-emprendimiento-creatividad-lean_stepienybarno--180x110.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2014\/01\/jose-pico-etudio-d3-emprendimiento-creatividad-lean_stepienybarno--316x192.jpg 316w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p align=\"left\">El arquitecto Jos\u00e9 Pico <a href=\"https:\/\/twitter.com\/picoj\">@picoj<\/a> , entre otras cosas responsable del estudio <a href=\"http:\/\/www.de3.es\/\">D3<\/a>, nos habla de nuevas formas de emprender, mucho m\u00e1s ligeras y \u00e1giles que van al coraz\u00f3n de la idea.<\/p>\n<p align=\"left\">Sabias y entusiastas palabras de un arquitecto que est\u00e1 entendiendo los nuevos tiempos que corren.<\/p>\n<p align=\"left\"><!--more--><\/p>\n<p align=\"left\">\n<p align=\"left\">\n<p align=\"left\">\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.youtube.com\/watch?v=pPIYsSCNfNs&amp;sns=tw\"><strong>Acceder a la informaci\u00f3n.<\/strong><\/a><\/p>\n<p align=\"left\">\n<blockquote>\n<p align=\"left\">Post relacionados:<\/p>\n<p align=\"left\"><a href=\"https:\/\/stepienybarno.es\/blog\/2014\/01\/20\/curso-online-de-identidad-digital-para-arquitectos\/\">CURSO ONLINE DE IDENTIDAD DIGITAL PARA ARQUITECTOS<\/a><\/p>\n<p align=\"left\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"rfgGz3E0SD\"><p><a href=\"https:\/\/stepienybarno.es\/blog\/2014\/01\/20\/curso-online-de-identidad-digital-para-arquitectos\/\">CURSO ONLINE DE IDENTIDAD DIGITAL PARA ARQUITECTOS.<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abCURSO ONLINE DE IDENTIDAD DIGITAL PARA ARQUITECTOS.\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" src=\"https:\/\/stepienybarno.es\/blog\/2014\/01\/20\/curso-online-de-identidad-digital-para-arquitectos\/embed\/#?secret=rfgGz3E0SD\" data-secret=\"rfgGz3E0SD\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<\/blockquote>\n<p align=\"left\">\n<p align=\"left\">\n<p align=\"left\">Noticia seleccionada por el Canal de arquitectura STEPIENYBARNO.<\/p>\n<p align=\"left\"><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\">STEPIENYBARNO EN LINKEDIN<\/a><\/p>\n<p align=\"left\"><a href=\"http:\/\/twitter.com\/stepienybarno\/stepienybarno\">STEPIENYBARNO EN TWITTER<\/a><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">STEPIENYBARNO EN FACEBOOK<\/a><\/p>\n<p align=\"left\">\n<p align=\"left\">*Stepienybarno est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p align=\"left\">Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n (comunicaci\u00f3n y difusi\u00f3n) y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p align=\"left\">A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a> y redactores de <a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\">LA CIUDAD VIVA<\/a>.<\/p>\n<p align=\"left\">\n<p align=\"left\">* Los editores de esta publicaci\u00f3n digital no nos hacemos cargo de de los comentarios y\u00a0 conceptos vertidos en los textos firmados por otras personas, siendo \u00e9stos de responsabilidad exclusiva de sus autores.<\/p>\n<p align=\"left\">\n<p align=\"left\">* Tu comentario podr\u00e1 ser moderado, por lo tanto, aunque aparezca inmediatamente al ser publicado en la entrada, los editores de esta publicaci\u00f3n digital nos reservamos el derecho tanto de editarlo (si fuera necesario, para hacerlo m\u00e1s legible) como de eliminarlo en el caso de que se usen expresiones incorrectas (descalificaciones, palabras malsonantes\u2026). A su vez, si quieres comentar desde el anonimato puedes hacerlo, aunque, nosotros personalmente, agradecemos que tod@s nos podamos identificar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El arquitecto Jos\u00e9 Pico @picoj , entre otras cosas responsable del estudio D3, nos habla de nuevas formas de emprender, mucho m\u00e1s ligeras y \u00e1giles que van al coraz\u00f3n de la idea.<\/p>\n<p>Sabias y entusiastas palabras de un arquitecto que est\u00e1 entendiendo los nuevos tiempos que corren.<\/p>\n<p>(m\u00e1s&#8230;)<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[34,244,27],"tags":[4274,2782,1959,2781],"series":[],"class_list":["post-12199","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-canal-de-arquitectura","category-nueva-era-digital","tag-actualidad","tag-d3","tag-emprendimiento","tag-jose-pico"],"aioseo_notices":[],"episode_featured_image":false,"episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"LTIqTdfLt3\"><a href=\"https:\/\/stepienybarno.es\/blog\/2014\/01\/22\/jose-pico-hablando-de-emprendimiento\/\">JOS\u00c9 MANUEL PICO HABLANDO DE EMPRENDIMIENTO<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2014\/01\/22\/jose-pico-hablando-de-emprendimiento\/embed\/#?secret=LTIqTdfLt3\" width=\"500\" height=\"350\" title=\"\u00abJOS\u00c9 MANUEL PICO HABLANDO DE EMPRENDIMIENTO\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"LTIqTdfLt3\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/12199"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=12199"}],"version-history":[{"count":3,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/12199\/revisions"}],"predecessor-version":[{"id":12202,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/12199\/revisions\/12202"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=12199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=12199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=12199"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=12199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}