{"id":14047,"date":"2014-06-13T22:36:15","date_gmt":"2014-06-13T20:36:15","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=14047"},"modified":"2014-06-13T22:39:18","modified_gmt":"2014-06-13T20:39:18","slug":"alvaro-siza-en-el-iii-congreso-arquitectura-necesaria-de-pamplona","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2014\/06\/13\/alvaro-siza-en-el-iii-congreso-arquitectura-necesaria-de-pamplona\/","title":{"rendered":"\u00c1LVARO SIZA EN EL III CONGRESO ARQUITECTURA NECESARIA DE PAMPLONA."},"content":{"rendered":"<p align=\"left\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2014\/06\/siza-alvaro-arquitectura-necesaria-pamplona-verdu-stepienybarno-..jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14048\" title=\"siza-alvaro-arquitectura-necesaria-pamplona-verdu-stepienybarno  .\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2014\/06\/siza-alvaro-arquitectura-necesaria-pamplona-verdu-stepienybarno-..jpg\" alt=\"siza-alvaro-arquitectura-necesaria-pamplona-verdu-stepienybarno  .\" width=\"350\" height=\"263\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2014\/06\/siza-alvaro-arquitectura-necesaria-pamplona-verdu-stepienybarno-..jpg 350w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2014\/06\/siza-alvaro-arquitectura-necesaria-pamplona-verdu-stepienybarno-.-180x135.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2014\/06\/siza-alvaro-arquitectura-necesaria-pamplona-verdu-stepienybarno-.-316x237.jpg 316w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p align=\"left\">Luis Fern\u00e1ndez Galiano ide\u00f3 un cartel para el congreso que pod\u00eda ser m\u00e1s o menos discutible (la presencia del arquitecto m\u00e1s grande todos, no pegaba ni con cola), pero lo que es indiscutible es que ha acertado de lleno con traca final del congreso.<\/p>\n<p align=\"left\">Hacer que Siza cierre el evento, es jugar a caballo ganador y el arquitecto portugu\u00e9s no defraud\u00f3.<\/p>\n<p align=\"left\">\n<p align=\"left\"><!--more--><\/p>\n<p align=\"left\">\n<p align=\"left\">Como bien sab\u00e9is los que nos segu\u00eds hace tiempo, Siza es nuestro arquitecto de cabecera, as\u00ed que hemos pillado el d\u00eda con m\u00e1s ganas que nunca. La charla estuvo bien, no se le nota la edad y, de hecho, parece m\u00e1s l\u00facido que nunca. Fue el \u00fanico arquitecto de todo el congreso que habl\u00f3 de temas m\u00e1s pragm\u00e1ticos y que ata\u00f1en al d\u00eda del colectivo de arquitectos.<\/p>\n<p align=\"left\">A su vez, aunque, seg\u00fan \u00e9l, estaba muy pesimista, no faltaron palabras de aliento, sobre todo para los m\u00e1s j\u00f3venes. En fin, que siempre es emocionante ver en directo a un arquitecto que ya ha entrado en las p\u00e1ginas de oro de la historia de la arquitectura.<\/p>\n<blockquote>\n<p align=\"left\"><strong>Acceder a los v\u00eddeos:<\/strong><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.youtube.com\/watch?v=f74oEh2C-Lg\">V\u00eddeo charla 1<\/a><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.youtube.com\/watch?v=f74oEh2C-Lg\">V\u00eddeo charla 2<\/a><\/p>\n<p align=\"left\">\n<p align=\"left\"><a href=\"https:\/\/www.youtube.com\/watch?v=lKXVzl2kp9Y\">V\u00eddeo debate 1<\/a><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.youtube.com\/watch?v=-CkjnX5uxWI\">V\u00eddeo debate 2<\/a><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.youtube.com\/watch?v=v2oYAwoUfNQ\">V\u00eddeo debate 3<\/a><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.youtube.com\/watch?v=Jhv_2SBU2fc\">V\u00eddeo debate 4<\/a><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.youtube.com\/watch?v=dUEsVajqkjo\">V\u00eddeo debate 5<\/a><\/p>\n<p align=\"left\">\n<p align=\"left\">\n<p align=\"left\">V\u00eddeo rueda de prensa, <a href=\"https:\/\/www.youtube.com\/watch?v=YHoH2cv2UmE\">AQU\u00cd<\/a><\/p>\n<\/blockquote>\n<p align=\"left\">\n<blockquote>\n<p align=\"left\"><strong>Post relacionados:<\/strong><\/p>\n<p>Post del congreso: III CONGRESO INTERNACIONAL ARQUITECTURA Y SOCIEDAD _ Arquitectura necesaria<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"aDsX1mDyk4\"><p><a href=\"https:\/\/stepienybarno.es\/blog\/2014\/04\/09\/iii-congreso-internacional-arquitectura-y-sociedad-_-arquitectura-necesaria\/\">III CONGRESO INTERNACIONAL ARQUITECTURA Y SOCIEDAD _ Arquitectura necesaria<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abIII CONGRESO INTERNACIONAL ARQUITECTURA Y SOCIEDAD _ Arquitectura necesaria\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" src=\"https:\/\/stepienybarno.es\/blog\/2014\/04\/09\/iii-congreso-internacional-arquitectura-y-sociedad-_-arquitectura-necesaria\/embed\/#?secret=aDsX1mDyk4\" data-secret=\"aDsX1mDyk4\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Ponentes: http:\/\/arquitecturaysociedad.org\/congreso-arquitectura-necesaria\/?idioma=_es<\/p><\/blockquote>\n<p align=\"left\"><strong> <\/strong><\/p>\n<p>* Este art\u00edculo ha sido escrito con car\u00e1cter divulgativo y sin ning\u00fan tipo de \u00e1nimo de lucro. As\u00ed que, si te apetece compartirlo en cualquier otro medio, estaremos encantados de que lo hagas siempre y cuando cites el lugar donde lo has encontrado.<\/p>\n<p><a href=\"https:\/\/twitter.com\/stepienybarno\">STEPIENYBARNO EN TWITTER _ @stepienybarno<\/a><\/p>\n<p><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\">STEPIENYBARNO EN LINKEDIN<\/a><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">STEPIENYBARNO EN FACEBOOK<\/a><\/p>\n<p>* Stepienybarno est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p>Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p>A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a> y redactores de <a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\">LA CIUDAD VIVA<\/a>.<\/p>\n<p>* Los editores de esta publicaci\u00f3n digital no nos hacemos cargo de de los comentarios y\u00a0 conceptos vertidos en los textos firmados por otras personas, siendo \u00e9stos de responsabilidad exclusiva de sus autores.<\/p>\n<p>* Tu comentario pudiera ser moderado, por lo tanto, aunque aparezca inmediatamente al ser publicado en la entrada, los editores de esta publicaci\u00f3n digital nos reservamos el derecho tanto de editarlo (si fuera necesario, para hacerlo m\u00e1s legible) como de eliminarlo en el caso de que se usen expresiones incorrectas (descalificaciones, palabras malsonantes\u2026). A su vez, si quieres comentar desde el anonimato puedes hacerlo, aunque, nosotros personalmente, agradecemos que tod@s nos podamos identificar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luis Fern\u00e1ndez Galiano ide\u00f3 un cartel para el congreso que pod\u00eda ser m\u00e1s o menos discutible (la presencia del arquitecto m\u00e1s grande todos, no pegaba ni con cola), pero lo que es indiscutible es que ha acertado de lleno con traca final del congreso.<\/p>\n<p>Hacer que Siza cierre el evento, es jugar a caballo ganador y el arquitecto portugu\u00e9s no defraud\u00f3.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[34,244],"tags":[121,2985],"series":[],"class_list":["post-14047","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-canal-de-arquitectura","tag-alvaro-siza","tag-congreso-internacional-arquitectura-y-sociedad"],"aioseo_notices":[],"episode_featured_image":false,"episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"zNlAHlVLgN\"><a href=\"https:\/\/stepienybarno.es\/blog\/2014\/06\/13\/alvaro-siza-en-el-iii-congreso-arquitectura-necesaria-de-pamplona\/\">\u00c1LVARO SIZA EN EL III CONGRESO ARQUITECTURA NECESARIA DE PAMPLONA.<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2014\/06\/13\/alvaro-siza-en-el-iii-congreso-arquitectura-necesaria-de-pamplona\/embed\/#?secret=zNlAHlVLgN\" width=\"500\" height=\"350\" title=\"\u00ab\u00c1LVARO SIZA EN EL III CONGRESO ARQUITECTURA NECESARIA DE PAMPLONA.\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"zNlAHlVLgN\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/14047"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=14047"}],"version-history":[{"count":5,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/14047\/revisions"}],"predecessor-version":[{"id":14050,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/14047\/revisions\/14050"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=14047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=14047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=14047"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=14047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}