{"id":15645,"date":"2015-01-26T18:01:08","date_gmt":"2015-01-26T16:01:08","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=15645"},"modified":"2015-01-26T18:06:34","modified_gmt":"2015-01-26T16:06:34","slug":"casa-farallo-proyectodeldia","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2015\/01\/26\/casa-farallo-proyectodeldia\/","title":{"rendered":"CASA FARALL\u00d3 #ProyectoDelDia"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15646\" title=\"Stepienybarno- FARALL\u00d3-I\u00f1aki Alonso y \u00c1lvaro Guerrero-Satt arquitectos\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-350x233.jpg\" alt=\"Stepienybarno- FARALL\u00d3-I\u00f1aki Alonso y \u00c1lvaro Guerrero-Satt arquitectos\" width=\"350\" height=\"233\" \/><\/a><\/p>\n<p>Por:\u00a0I\u00f1aki Alonso y \u00c1lvaro Guerrero _ Satt arquitectos.<\/p>\n<p>Foto: ojo vivo fotos.<\/p>\n<p><!--more--><\/p>\n<p>\u201c(\u2026) En el exterior, se dise\u00f1\u00f3 tambi\u00e9n un segundo patio, previo al acceso a la casa, con una serie de bancales y una piscina pensada desde un punto de vista po\u00e9tico: el acto de ba\u00f1arse se convierte en un recorrido a lo largo de toda la piscina para, al final, aparecer asomado a una ventana sobre el barranco, en esta ventana aparecen una vistas impresionantes y se recrea un peque\u00f1o lugar de estancia en el agua, con unos bancos sumergidos y una sombra.\u201d<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-15647\" title=\"Stepienybarno- FARALL\u00d3-I\u00f1aki Alonso y \u00c1lvaro Guerrero-Satt arquitectos 2\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-2.jpg\" alt=\"Stepienybarno- FARALL\u00d3-I\u00f1aki Alonso y \u00c1lvaro Guerrero-Satt arquitectos 2\" width=\"709\" height=\"472\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-2.jpg 709w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-2-180x120.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-2-550x366.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-2-316x210.jpg 316w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-15648\" title=\"Stepienybarno- FARALL\u00d3-I\u00f1aki Alonso y \u00c1lvaro Guerrero-Satt arquitectos 1\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-1.jpg\" alt=\"Stepienybarno- FARALL\u00d3-I\u00f1aki Alonso y \u00c1lvaro Guerrero-Satt arquitectos 1\" width=\"709\" height=\"460\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-1.jpg 709w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-1-180x117.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-1-550x357.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/01\/Stepienybarno-FARALL\u00d3-I\u00f1aki-Alonso-y-\u00c1lvaro-Guerrero-Satt-arquitectos-1-316x205.jpg 316w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/><\/a><\/p>\n<blockquote>\n<p style=\"text-align: center;\"><strong>Acceder al post,<a href=\"http:\/\/www.ecohabitar.org\/casa-farallo-adaptacion-al-entorno\/\"> AQU\u00cd<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Web de los autores: http:\/\/www.satt.es\/<\/strong><\/p>\n<\/blockquote>\n<p align=\"left\">\n<blockquote>\n<p align=\"left\"><strong>Post relacionados:<\/strong><\/p>\n<p align=\"left\">#ProyectoDelDia<\/p>\n<p align=\"left\"><a href=\"https:\/\/stepienybarno.es\/blog\/tag\/proyectodeldia\/\">https:\/\/stepienybarno.es\/blog\/tag\/proyectodeldia\/<\/a><\/p>\n<\/blockquote>\n<p align=\"left\"><span style=\"color: #888888;\"><em>Noticia seleccionada por el Canal de arquitectura STEPIENYBARNO.<\/em><\/span><\/p>\n<p><a href=\"https:\/\/twitter.com\/stepienybarno\"><span style=\"color: #888888;\"><em>STEPIENYBARNO EN TWITTER _ @stepienybarno<\/em><\/span><\/a><\/p>\n<p align=\"left\"><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\"><span style=\"color: #888888;\"><em>STEPIENYBARNO EN LINKEDIN<\/em><\/span><\/a><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\"><span style=\"color: #888888;\"><em>STEPIENYBARNO EN FACEBOOK<\/em><\/span><\/a><\/p>\n<p align=\"left\"><span style=\"color: #888888;\"><em>*Stepienybarno est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/em><\/span><\/p>\n<p align=\"left\"><span style=\"color: #888888;\"><em>Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n (comunicaci\u00f3n y difusi\u00f3n) y la redacci\u00f3n de proyectos de arquitectura.<\/em><\/span><\/p>\n<p align=\"left\"><span style=\"color: #888888;\"><em>A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a> y redactores de <a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\">LA CIUDAD VIVA<\/a>.<\/em><\/span><\/p>\n<p align=\"left\"><span style=\"color: #888888;\"><em>* Los editores de esta publicaci\u00f3n digital no nos hacemos cargo de de los comentarios y\u00a0 conceptos vertidos en los textos firmados por otras personas, siendo \u00e9stos de responsabilidad exclusiva de sus autores.<\/em><\/span><\/p>\n<p align=\"left\"><span style=\"color: #888888;\"><em>* Tu comentario podr\u00e1 ser moderado, por lo tanto, aunque aparezca inmediatamente al ser publicado en la entrada, los editores de esta publicaci\u00f3n digital nos reservamos el derecho tanto de editarlo (si fuera necesario, para hacerlo m\u00e1s legible) como de eliminarlo en el caso de que se usen expresiones incorrectas (descalificaciones, palabras malsonantes\u2026). A su vez, si quieres comentar desde el anonimato puedes hacerlo, aunque, nosotros personalmente, agradecemos que tod@s nos podamos identificar.<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por:\u00a0I\u00f1aki Alonso y \u00c1lvaro Guerrero _ Satt arquitectos. Foto: ojo<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[34,244],"tags":[3289,377,3290],"series":[],"class_list":["post-15645","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-canal-de-arquitectura","tag-alvaro-guerrero","tag-inaki-alonso","tag-satt-arquitectos"],"aioseo_notices":[],"episode_featured_image":false,"episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"khGGyMoSTi\"><a href=\"https:\/\/stepienybarno.es\/blog\/2015\/01\/26\/casa-farallo-proyectodeldia\/\">CASA FARALL\u00d3 #ProyectoDelDia<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2015\/01\/26\/casa-farallo-proyectodeldia\/embed\/#?secret=khGGyMoSTi\" width=\"500\" height=\"350\" title=\"\u00abCASA FARALL\u00d3 #ProyectoDelDia\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"khGGyMoSTi\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/15645"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=15645"}],"version-history":[{"count":5,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/15645\/revisions"}],"predecessor-version":[{"id":15651,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/15645\/revisions\/15651"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=15645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=15645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=15645"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=15645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}