{"id":17580,"date":"2015-06-01T19:30:24","date_gmt":"2015-06-01T17:30:24","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=17580"},"modified":"2015-06-01T13:33:05","modified_gmt":"2015-06-01T11:33:05","slug":"proyectar-la-ventana","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2015\/06\/01\/proyectar-la-ventana\/","title":{"rendered":"PROYECTAR LA VENTANA"},"content":{"rendered":"<p><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/06\/Stepienybarno-Blog-Stepien-y-barno-veredes-miguel-angel-diaz-camacho.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17581\" title=\"Stepienybarno-Blog-Stepien-y-barno-veredes-miguel-angel-diaz-camacho\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/06\/Stepienybarno-Blog-Stepien-y-barno-veredes-miguel-angel-diaz-camacho.jpg\" alt=\"Stepienybarno-Blog-Stepien-y-barno-veredes-miguel-angel-diaz-camacho\" width=\"500\" height=\"444\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/06\/Stepienybarno-Blog-Stepien-y-barno-veredes-miguel-angel-diaz-camacho.jpg 500w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/06\/Stepienybarno-Blog-Stepien-y-barno-veredes-miguel-angel-diaz-camacho-180x160.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/06\/Stepienybarno-Blog-Stepien-y-barno-veredes-miguel-angel-diaz-camacho-316x281.jpg 316w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Por <a href=\"http:\/\/www.madc-arquitectos.com\/\" target=\"_blank\">Miguel \u00c1ngel D\u00edaz Camacho<\/a> Desde <a href=\"http:\/\/veredes.es\/blog\" target=\"_blank\">Veredes<\/a><\/p>\n<p><!--more--><\/p>\n<p>\u201cLa geometr\u00eda del hueco incide simult\u00e1neamente tanto en la variable perceptiva interior \u2013 exterior, como en la iluminaci\u00f3n de una estancia o la propia soluci\u00f3n constructiva de la envolvente. El tradicional hueco vertical, asociado a la construcci\u00f3n de muros portantes, define un umbral espacial y emocional entre la naturaleza exterior y el espacio interior en penumbra; el hueco horizontal propuesto por Le Corbusier durante los primeros a\u00f1os 20, habilita una iluminaci\u00f3n homog\u00e9nea y brillante al tiempo que representa \u2018la fachada libre\u2019, el triunfo de la t\u00e9cnica que habilita la independencia entre cerramiento y estructura<sup>1<\/sup>.<\/p>\n<p>La \u2018secularizaci\u00f3n\u2019 del espacio interior propuesta por Le Corbusier es motivo de graves y p\u00fablicas controversias, como la muy conocida entre el propio arquitecto suizo y el que fuera su maestro en el uso del hormig\u00f3n, Auguste Perret<sup>2<\/sup>.\u00a0 (\u2026)\u201d<\/p>\n<blockquote>\n<p align=\"center\">Acceder al v\u00eddeo, <a href=\"https:\/\/www.youtube.com\/watch?t=115&amp;v=vaVl8_KM2rI\" target=\"_blank\">AQU\u00cd<\/a><\/p>\n<\/blockquote>\n<p><span style=\"color: #888888;\"> <\/span><\/p>\n<p><em><span style=\"color: #888888;\">Noticia seleccionada por el Canal de arquitectura STEPIENYBARNO.<\/span><\/em><\/p>\n<p><em><span style=\"text-decoration: underline;\"><a href=\"https:\/\/twitter.com\/stepienybarno\" target=\"_blank\">STEPIENYBARNO EN TWITTER _ @stepienybarno<\/a><\/span><\/em><\/p>\n<p><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\" target=\"_blank\"><em>STEPIENYBARNO EN LINKEDIN<\/em><\/a><\/span><\/p>\n<p><em><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.facebook.com\/StepienybarnoCANAL\" target=\"_blank\">STEPIENYBARNO EN FACEBOOK<\/a><\/span><\/em><\/p>\n<p><em><span style=\"color: #888888;\">*Stepienybarno est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/span><\/em><\/p>\n<p><em><span style=\"color: #888888;\">Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n (comunicaci\u00f3n y difusi\u00f3n) y la redacci\u00f3n de proyectos de arquitectura.<\/span><\/em><\/p>\n<p><span style=\"color: #888888;\"><em>A su vez, somos socios cofundadores de<\/em><em> <\/em><\/span><em><a href=\"http:\/\/sinergiasostenible.org\/\" target=\"_blank\">SINERGIA SOSTENIBLE<\/a><span style=\"color: #888888;\">, redactores de<\/span><\/em><em><span style=\"color: #888888;\"> <\/span><\/em><em><a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\" target=\"_blank\">LA CIUDAD VIVA<\/a><\/em><span style=\"color: #888888;\"><em> <\/em><em>y directores del blog de<\/em><em> <\/em><\/span><em><a href=\"http:\/\/blogfundacion.arquia.es\/\" target=\"_blank\">FUNDACI\u00d3N ARQUIA<\/a><span style=\"color: #888888;\">.<\/span><\/em><\/p>\n<p><em><span style=\"color: #888888;\">* Los editores de esta publicaci\u00f3n digital no nos hacemos cargo de de los comentarios y\u00a0 conceptos vertidos en los textos firmados por otras personas, siendo \u00e9stos de responsabilidad exclusiva de sus autores.<\/span><\/em><\/p>\n<p><em><span style=\"color: #888888;\">* Tu comentario podr\u00e1 ser moderado, por lo tanto, aunque aparezca inmediatamente al ser publicado en la entrada, los editores de esta publicaci\u00f3n digital nos reservamos el derecho tanto de editarlo (si fuera necesario, para hacerlo m\u00e1s legible) como de eliminarlo en el caso de que se usen expresiones incorrectas (descalificaciones, palabras malsonantes\u2026). A su vez, si quieres comentar desde el anonimato puedes hacerlo, aunque, nosotros personalmente, agradecemos que tod@s nos podamos identificar.<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Miguel \u00c1ngel D\u00edaz Camacho Desde Veredes<\/p>\n<p>(m\u00e1s&#8230;)<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[244],"tags":[952,2765],"series":[],"class_list":["post-17580","post","type-post","status-publish","format-standard","hentry","category-canal-de-arquitectura","tag-miguel-angel-diaz-camacho","tag-veredes-arquitectura-y-divulgacion"],"aioseo_notices":[],"episode_featured_image":false,"episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"fFlHPN9gGt\"><a href=\"https:\/\/stepienybarno.es\/blog\/2015\/06\/01\/proyectar-la-ventana\/\">PROYECTAR LA VENTANA<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2015\/06\/01\/proyectar-la-ventana\/embed\/#?secret=fFlHPN9gGt\" width=\"500\" height=\"350\" title=\"\u00abPROYECTAR LA VENTANA\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"fFlHPN9gGt\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/17580"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=17580"}],"version-history":[{"count":2,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/17580\/revisions"}],"predecessor-version":[{"id":17583,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/17580\/revisions\/17583"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=17580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=17580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=17580"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=17580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}