{"id":19635,"date":"2015-12-07T13:21:12","date_gmt":"2015-12-07T11:21:12","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=19635"},"modified":"2015-12-24T14:56:34","modified_gmt":"2015-12-24T12:56:34","slug":"vo-trong-nghias-oversized-bamboo-domes-proyectodeldia","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2015\/12\/07\/vo-trong-nghias-oversized-bamboo-domes-proyectodeldia\/","title":{"rendered":"VO TRONG NGHIA&#8217;S OVERSIZED BAMBOO DOMES #ProyectoDelD\u00eda"},"content":{"rendered":"<p><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19639\" title=\"stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes.jpg\" alt=\"stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes\" width=\"500\" height=\"333\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes.jpg 500w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-180x120.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-316x210.jpg 316w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><span style=\"font-weight: normal;\">Por Vo Trong Nghia Architects Desde <a href=\"http:\/\/www.designboom.com\/\" target=\"_blank\">designboom<\/a><\/span><\/p>\n<p><!--more--><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19636\" title=\"stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-2\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-2.jpg\" alt=\"stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-2\" width=\"500\" height=\"333\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-2.jpg 500w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-2-180x120.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-2-316x210.jpg 316w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19637\" title=\"stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-3\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-3.jpg\" alt=\"stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-3\" width=\"500\" height=\"333\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-3.jpg 500w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-3-180x120.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-3-316x210.jpg 316w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19638\" title=\"stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-4\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-4.jpg\" alt=\"stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-4\" width=\"500\" height=\"333\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-4.jpg 500w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-4-180x120.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2015\/12\/stepienybarno-stepien-y-barno-proyecto-del-dia-designboom-bamboo-domes-4-316x210.jpg 316w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<blockquote>\n<p style=\"text-align: center;\">M\u00e1s sobre el proyecto,\u00a0<a href=\"http:\/\/www.designboom.com\/architecture\/vo-trong-nghia-architects-diamond-island-condo-pavilions-ho-chi-minh-vietnam-12-03-2015\/\" target=\"_blank\">AQU\u00cd<\/a><\/p>\n<\/blockquote>\n<p align=\"center\">\n<blockquote>\n<p align=\"center\">Post relacionados: #ProyectoDelDia\u00a0<a href=\"https:\/\/stepienybarno.es\/blog\/tag\/proyectodeldia\/\" target=\"_blank\">https:\/\/stepienybarno.es\/blog\/tag\/proyectodeldia\/<\/a><\/p>\n<\/blockquote>\n<p align=\"center\">\n<p align=\"center\">\n<p align=\"center\"><strong> <\/strong><\/p>\n<p><em><span style=\"color: #999999;\">Noticia seleccionada por el Canal de arquitectura STEPIENYBARNO.<\/span><\/em><\/p>\n<p><a href=\"https:\/\/twitter.com\/stepienybarno\" target=\"_blank\"><em>STEPIENYBARNO EN TWITTER _ @stepienybarno<\/em><\/a><\/p>\n<p><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\" target=\"_blank\"><em>STEPIENYBARNO EN LINKEDIN<\/em><\/a><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\" target=\"_blank\"><em>STEPIENYBARNO EN FACEBOOK<\/em><\/a><\/p>\n<p><em><span style=\"color: #999999;\">*Stepienybarno est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/span><\/em><\/p>\n<p><em><span style=\"color: #999999;\">Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n (comunicaci\u00f3n y difusi\u00f3n) y la redacci\u00f3n de proyectos de arquitectura.<\/span><\/em><\/p>\n<p><span style=\"color: #999999;\"><em>A su vez, somos socios cofundadores de<\/em><em> <\/em><\/span><a href=\"http:\/\/sinergiasostenible.org\/\" target=\"_blank\"><em>SINERGIA SOSTENIBLE<\/em><\/a><em><span style=\"color: #999999;\">, redactores de<\/span><\/em><em> <\/em><a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\" target=\"_blank\"><em>LA CIUDAD VIVA<\/em><\/a><em> <\/em><span style=\"color: #999999;\"><em>y directores del blog de<\/em><em> <\/em><\/span><a href=\"http:\/\/blogfundacion.arquia.es\/\" target=\"_blank\"><em>FUNDACI\u00d3N ARQUIA<span style=\"color: #999999;\">.<\/span><\/em><\/a><\/p>\n<p><em><span style=\"color: #999999;\">* Los editores de esta publicaci\u00f3n digital no nos hacemos cargo de de los comentarios y\u00a0 conceptos vertidos en los textos firmados por otras personas, siendo \u00e9stos de responsabilidad exclusiva de sus autores.<\/span><\/em><\/p>\n<p><em><span style=\"color: #999999;\">* Tu comentario podr\u00e1 ser moderado, por lo tanto, aunque aparezca inmediatamente al ser publicado en la entrada, los editores de esta publicaci\u00f3n digital nos reservamos el derecho tanto de editarlo (si fuera necesario, para hacerlo m\u00e1s legible) como de eliminarlo en el caso de que se usen expresiones incorrectas (descalificaciones, palabras malsonantes\u2026). A su vez, si quieres comentar desde el anonimato puedes hacerlo, aunque, nosotros personalmente, agradecemos que tod@s nos podamos identificar.<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Vo Trong Nghia Architects Desde designboom <\/p>\n<p>(m\u00e1s&#8230;)<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[244],"tags":[4277,3694,3821],"series":[],"class_list":["post-19635","post","type-post","status-publish","format-standard","hentry","category-canal-de-arquitectura","tag-proyecto-de-arquitectura-del-dia","tag-designboom","tag-vo-trong-nghia-architects"],"aioseo_notices":[],"episode_featured_image":false,"episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"xwJOn1T2lA\"><a href=\"https:\/\/stepienybarno.es\/blog\/2015\/12\/07\/vo-trong-nghias-oversized-bamboo-domes-proyectodeldia\/\">VO TRONG NGHIA&#8217;S OVERSIZED BAMBOO DOMES #ProyectoDelD\u00eda<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2015\/12\/07\/vo-trong-nghias-oversized-bamboo-domes-proyectodeldia\/embed\/#?secret=xwJOn1T2lA\" width=\"500\" height=\"350\" title=\"\u00abVO TRONG NGHIA&#8217;S OVERSIZED BAMBOO DOMES #ProyectoDelD\u00eda\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"xwJOn1T2lA\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/19635"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=19635"}],"version-history":[{"count":3,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/19635\/revisions"}],"predecessor-version":[{"id":19641,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/19635\/revisions\/19641"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=19635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=19635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=19635"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=19635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}