{"id":21300,"date":"2016-03-14T16:01:03","date_gmt":"2016-03-14T14:01:03","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=21300"},"modified":"2016-03-14T10:39:18","modified_gmt":"2016-03-14T08:39:18","slug":"acceso-al-centro-historico-de-gironella-proyectodeldia","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2016\/03\/14\/acceso-al-centro-historico-de-gironella-proyectodeldia\/","title":{"rendered":"ACCESO AL CENTRO HIST\u00d3RICO DE GIRONELLA #ProyectoDelD\u00eda"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-21307\" title=\"stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-466x700.jpg\" alt=\"stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura\" width=\"466\" height=\"700\" \/><\/p>\n<p>Por\u00a0<a href=\"http:\/\/carlesenrich.com\/es\/\" target=\"_blank\">Carles Enrich<\/a> Fotograf\u00eda <a href=\"http:\/\/www.adriagoula.com\/\" target=\"_blank\">Adri\u00e0 Goula<br \/>\n<\/a>Desde <a href=\"http:\/\/www.plataformaarquitectura.cl\/\" target=\"_blank\">Plataforma Arquitectura<\/a><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-21304\" title=\"stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-2\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-21.jpg\" alt=\"stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-2\" width=\"500\" height=\"250\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-21.jpg 500w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-21-180x90.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-21-316x158.jpg 316w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-21303 aligncenter\" title=\"stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-3\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-31-466x700.jpg\" alt=\"stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-3\" width=\"500\" height=\"700\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-21305\" title=\"stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-4\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-4.jpg\" alt=\"stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-4\" width=\"500\" height=\"250\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-4.jpg 500w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-4-180x90.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-4-316x158.jpg 316w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-21306\" title=\"stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-5\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-5.jpg\" alt=\"stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-5\" width=\"500\" height=\"250\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-5.jpg 500w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-5-180x90.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/03\/stepienybarno-proyecto-del-dia-adria-goula-carles-enrich-plataforma-arquitectura-5-316x158.jpg 316w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<blockquote>\n<p style=\"text-align: center;\">M\u00e1s sobre el proyecto, <a href=\"http:\/\/www.plataformaarquitectura.cl\/cl\/776906\/acceso-al-centro-historico-de-gironella-carles-enrich\" target=\"_blank\">AQU\u00cd<\/a><\/p>\n<\/blockquote>\n<p align=\"center\">\n<blockquote>\n<p style=\"text-align: center;\">Post relacionados: #ProyectoDelDia\u00a0<a href=\"https:\/\/stepienybarno.es\/blog\/tag\/proyectodeldia\/\" target=\"_blank\">https:\/\/stepienybarno.es\/blog\/tag\/proyectodeldia\/<\/a><\/p>\n<\/blockquote>\n<p align=\"center\">\n<p align=\"center\">\n<p><em><span style=\"color: #888888;\">Noticia seleccionada por el Canal de arquitectura STEPIENYBARNO.<\/span><\/em><\/p>\n<p><a href=\"https:\/\/twitter.com\/stepienybarno\"><em>STEPIENYBARNO EN TWITTER _ @stepienybarno<\/em><\/a><\/p>\n<p><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\"><em>STEPIENYBARNO EN LINKEDIN<\/em><\/a><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\"><em>STEPIENYBARNO EN FACEBOOK<\/em><\/a><em> <\/em><\/p>\n<p><em><span style=\"color: #888888;\">*Stepienybarno est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/span><\/em><\/p>\n<p><em><span style=\"color: #888888;\">Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n (comunicaci\u00f3n y difusi\u00f3n) y la redacci\u00f3n de proyectos de arquitectura.<\/span><\/em><\/p>\n<p><em><span style=\"color: #888888;\">A su vez, somos socios cofundadores de<\/span><\/em><em> <\/em><a href=\"http:\/\/sinergiasostenible.org\/\"><em>SINERGIA SOSTENIBLE<\/em><\/a><em><span style=\"color: #888888;\">, redactores de<\/span><\/em><em> <\/em><a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\"><em>LA CIUDAD VIVA<\/em><\/a><em> <\/em><em><span style=\"color: #888888;\">y directores del blog de<\/span><\/em><em> <\/em><a href=\"http:\/\/blogfundacion.arquia.es\/\"><em>FUNDACI\u00d3N ARQUIA<span style=\"color: #888888;\">.<\/span><\/em><\/a><span style=\"color: #888888;\"><em> <\/em><\/span><\/p>\n<p><em><span style=\"color: #888888;\">* Los editores de esta publicaci\u00f3n digital no nos hacemos cargo de de los comentarios y\u00a0 conceptos vertidos en los textos firmados por otras personas, siendo \u00e9stos de responsabilidad exclusiva de sus autores.<\/span><\/em><\/p>\n<p><em><span style=\"color: #888888;\">* Tu comentario podr\u00e1 ser moderado, por lo tanto, aunque aparezca inmediatamente al ser publicado en la entrada, los editores de esta publicaci\u00f3n digital nos reservamos el derecho tanto de editarlo (si fuera necesario, para hacerlo m\u00e1s legible) como de eliminarlo en el caso de que se usen expresiones incorrectas (descalificaciones, palabras malsonantes\u2026). A su vez, si quieres comentar desde el anonimato puedes hacerlo, aunque, nosotros personalmente, agradecemos que tod@s nos podamos identificar.<\/span><\/em><\/p>\n<p><em> <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Carles Enrich Fotograf\u00eda Adri\u00e0 Goula<br \/>\nDesde Plataforma Arquitectura<\/p>\n<p>(m\u00e1s&#8230;)<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[3197,244],"tags":[4277,2457,3040,921],"series":[],"class_list":["post-21300","post","type-post","status-publish","format-standard","hentry","category-proyectodeldia","category-canal-de-arquitectura","tag-proyecto-de-arquitectura-del-dia","tag-adria-goula","tag-carles-enrich","tag-plataforma-arquitectura"],"aioseo_notices":[],"episode_featured_image":false,"episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"Owore1LOiv\"><a href=\"https:\/\/stepienybarno.es\/blog\/2016\/03\/14\/acceso-al-centro-historico-de-gironella-proyectodeldia\/\">ACCESO AL CENTRO HIST\u00d3RICO DE GIRONELLA #ProyectoDelD\u00eda<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2016\/03\/14\/acceso-al-centro-historico-de-gironella-proyectodeldia\/embed\/#?secret=Owore1LOiv\" width=\"500\" height=\"350\" title=\"\u00abACCESO AL CENTRO HIST\u00d3RICO DE GIRONELLA #ProyectoDelD\u00eda\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"Owore1LOiv\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/21300"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=21300"}],"version-history":[{"count":2,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/21300\/revisions"}],"predecessor-version":[{"id":21309,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/21300\/revisions\/21309"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=21300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=21300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=21300"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=21300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}