{"id":25098,"date":"2016-11-20T11:32:04","date_gmt":"2016-11-20T09:32:04","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=25098"},"modified":"2016-11-29T18:11:56","modified_gmt":"2016-11-29T16:11:56","slug":"ultimos-dias-de-tarifa-reducida-en-nuestro-curso-online-de-identidad-digital-para-arquitectos","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2016\/11\/20\/ultimos-dias-de-tarifa-reducida-en-nuestro-curso-online-de-identidad-digital-para-arquitectos\/","title":{"rendered":"\u00daLTIMOS D\u00cdAS DE TARIFA REDUCIDA EN NUESTRO CURSO ONLINE DE IDENTIDAD DIGITAL PARA #ARQUITECTOS"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>El pr\u00f3ximo mi\u00e9rcoles se acaba el periodo de tarifa reducida; as\u00ed que, si ves que tienes inter\u00e9s en el curso, te animamos a apuntarte cuanto antes.<\/p>\n<p>Adem\u00e1s, este a\u00f1o tiene pinta que colgaremos el cartel de no hay billetes \u00a1bastante antes de lo normal!!<\/p>\n<p><!--more--><\/p>\n<blockquote><p>\u201cUna de las cosas que m\u00e1s me ha gustado del curso es la facilidad a la hora de hacerlo. El poder organizarme las sesiones cada d\u00eda cuando me vengan bien gracias al formato que hab\u00e9is elegido es todo un \u00e9xito.\u201d<\/p>\n<p>Enrique Parra (Pedacicos Arquitectonicos)<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" width=\"911\" height=\"512\" src=\"https:\/\/www.youtube.com\/embed\/DfkTxtBJRNg?feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #ff0000;\">Toda la informaci\u00f3n<a href=\"http:\/\/cursoidentidaddigital.stepienybarno.es\/\" target=\"_blank\"> por aqu\u00ed.<\/a><\/span><\/h3>\n<h3 style=\"text-align: center;\"><a href=\"http:\/\/cursoidentidaddigital.stepienybarno.es\/\" target=\"_blank\"><span style=\"color: #ff0000;\">Sexta edici\u00f3n de nuestro curso online de Identidad Digital para arquitectos<\/span><\/a><\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>Autores del curso: <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> _ Agnieszka Stepien y Lorenzo Barn\u00f3<\/strong><\/p>\n<p style=\"text-align: center;\">Y como siempre, si te gust\u00f3 el post,\u00a0estar\u00eda genial que lo compartas\u00a0en tus redes sociales.<\/p>\n<p style=\"text-align: center;\">A su vez, si todav\u00eda no est\u00e1s suscrito a nuestra Newsletter, te animamos a hacerlo en la casilla que tienes al terminar este art\u00edculo.<\/p>\n<p style=\"text-align: center;\">\n<p>* Este art\u00edculo ha sido escrito con car\u00e1cter divulgativo y sin ning\u00fan tipo de \u00e1nimo de lucro. As\u00ed que, si te apetece compartirlo en cualquier otro medio, estaremos encantados de que lo hagas siempre y cuando cites el lugar donde lo has encontrado.<\/p>\n<p><a href=\"https:\/\/twitter.com\/stepienybarno\">STEPIENYBARNO EN TWITTER _ @stepienybarno<\/a><\/p>\n<p><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\">STEPIENYBARNO EN LINKEDIN<\/a><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">STEPIENYBARNO EN FACEBOOK<\/a><\/p>\n<p>* <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p>Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p>A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a>, redactores de <a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\">LA CIUDAD VIVA<\/a> y directores del blog de FUNDACI\u00d3N ARQUIA.<\/p>\n<p>* Los editores de esta publicaci\u00f3n digital no nos hacemos cargo de de los comentarios y\u00a0 conceptos vertidos en los textos firmados por otras personas, siendo \u00e9stos de responsabilidad exclusiva de sus autores.<\/p>\n<p>* Tu comentario pudiera ser moderado, por lo tanto, aunque aparezca inmediatamente al ser publicado en la entrada, los editores de esta publicaci\u00f3n digital nos reservamos el derecho tanto de editarlo (si fuera necesario, para hacerlo m\u00e1s legible) como de eliminarlo en el caso de que se usen expresiones incorrectas (descalificaciones, palabras malsonantes\u2026). A su vez, si quieres comentar desde el anonimato puedes hacerlo, aunque, nosotros personalmente, agradecemos que tod@s nos podamos identificar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; El pr\u00f3ximo mi\u00e9rcoles se acaba el periodo de tarifa<\/p>\n","protected":false},"author":2,"featured_media":24884,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[22],"tags":[4292],"series":[],"class_list":["post-25098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-identidad-digital-syb","tag-curso-de-identidad-digital-para-arquitectos"],"aioseo_notices":[],"episode_featured_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2016\/11\/curso-comunicacion-on-line-stepienybarno.png","episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"J1ENsqX8wY\"><a href=\"https:\/\/stepienybarno.es\/blog\/2016\/11\/20\/ultimos-dias-de-tarifa-reducida-en-nuestro-curso-online-de-identidad-digital-para-arquitectos\/\">\u00daLTIMOS D\u00cdAS DE TARIFA REDUCIDA EN NUESTRO CURSO ONLINE DE IDENTIDAD DIGITAL PARA #ARQUITECTOS<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2016\/11\/20\/ultimos-dias-de-tarifa-reducida-en-nuestro-curso-online-de-identidad-digital-para-arquitectos\/embed\/#?secret=J1ENsqX8wY\" width=\"500\" height=\"350\" title=\"\u00ab\u00daLTIMOS D\u00cdAS DE TARIFA REDUCIDA EN NUESTRO CURSO ONLINE DE IDENTIDAD DIGITAL PARA #ARQUITECTOS\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"J1ENsqX8wY\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/25098"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=25098"}],"version-history":[{"count":2,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/25098\/revisions"}],"predecessor-version":[{"id":25100,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/25098\/revisions\/25100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media\/24884"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=25098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=25098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=25098"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=25098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}