{"id":34713,"date":"2019-03-11T10:48:48","date_gmt":"2019-03-11T08:48:48","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=34713"},"modified":"2019-03-11T10:48:48","modified_gmt":"2019-03-11T08:48:48","slug":"conferencia-de-arata-isozaki-en-harvard","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2019\/03\/11\/conferencia-de-arata-isozaki-en-harvard\/","title":{"rendered":"Conferencia de Arata Isozaki en Harvard"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-34715\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/03\/Stepienybarno-arata-isozaki-harvardGSD-PostDelDia-01-550x347.jpg\" alt=\"\" width=\"550\" height=\"347\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/03\/Stepienybarno-arata-isozaki-harvardGSD-PostDelDia-01-550x347.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/03\/Stepienybarno-arata-isozaki-harvardGSD-PostDelDia-01-180x113.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/03\/Stepienybarno-arata-isozaki-harvardGSD-PostDelDia-01-316x199.jpg 316w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/03\/Stepienybarno-arata-isozaki-harvardGSD-PostDelDia-01.jpg 638w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/p>\n<h1>Conferenciante: Arata Isozaki<\/h1>\n<h2>Desde: <a href=\"https:\/\/www.youtube.com\/channel\/UCcA1don221rKq1EmbvQB27g\" target=\"_blank\" rel=\"noopener\">Harvard GSD<\/a><\/h2>\n<p><!--more--><\/p>\n<p>Compartimos una conferencia que imparti\u00f3 el Premio Pritzker 2019 en Harvard Graduate School of Design en Noviembre de 2007.<\/p>\n<p>El tema de la conferencia es <strong>Built\/Unbuilt.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Acceder al V\u00eddeo <a href=\"http:\/\/bit.ly\/2VKXIpC\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4>Si quieres conocer m\u00e1s sobre el arquitecto ARATA ISOZAKI \/ Premio Pritzker 2019 accede <a href=\"http:\/\/bit.ly\/2NZgBTr\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><em>Noticia seleccionada por el Canal de arquitectura STEPIENYBARNO.<\/em><\/p>\n<p><a href=\"https:\/\/twitter.com\/stepienybarno\" target=\"_blank\" rel=\"noopener\"><em>STEPIENYBARNO EN TWITTER _ @stepienybarno<\/em><\/a><\/p>\n<p><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\" target=\"_blank\" rel=\"noopener\"><em>STEPIENYBARNO EN LINKEDIN<\/em><\/a><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\" target=\"_blank\" rel=\"noopener\"><em>STEPIENYBARNO EN FACEBOOK<\/em><\/a><\/p>\n<p><em>*Stepienybarno est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/em><\/p>\n<p><em>Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n (comunicaci\u00f3n y difusi\u00f3n) y la redacci\u00f3n de proyectos de arquitectura.<\/em><\/p>\n<p><em>A su vez, somos socios cofundadores de<\/em>\u00a0<a href=\"http:\/\/sinergiasostenible.org\/\" target=\"_blank\" rel=\"noopener\"><em>SINERGIA SOSTENIBLE<\/em><\/a><em>, redactores de<\/em>\u00a0<a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\" target=\"_blank\" rel=\"noopener\"><em>LA CIUDAD VIVA<\/em><\/a>\u00a0<em>y directores del blog de<\/em><a href=\"http:\/\/blogfundacion.arquia.es\/\" target=\"_blank\" rel=\"noopener\"><em>FUNDACI\u00d3N ARQUIA.<\/em><\/a><\/p>\n<p><em>* Los editores de esta publicaci\u00f3n digital no nos hacemos cargo de de los comentarios y\u00a0 conceptos vertidos en los textos firmados por otras personas, siendo \u00e9stos de responsabilidad exclusiva de sus autores.<\/em><\/p>\n<p><em>* Tu comentario podr\u00e1 ser moderado, por lo tanto, aunque aparezca inmediatamente al ser publicado en la entrada, los editores de esta publicaci\u00f3n digital nos reservamos el derecho tanto de editarlo (si fuera necesario, para hacerlo m\u00e1s legible) como de eliminarlo en el caso de que se usen expresiones incorrectas (descalificaciones, palabras malsonantes\u2026). A su vez, si quieres comentar desde el anonimato puedes hacerlo, aunque, nosotros personalmente, agradecemos que tod@s nos podamos identificar.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conferenciante: Arata Isozaki Desde: Harvard GSD<\/p>\n","protected":false},"author":10,"featured_media":34715,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[244],"tags":[7123,7118,7127],"series":[],"class_list":["post-34713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canal-de-arquitectura","tag-pritzker2019","tag-arata-isozaki","tag-harvard-gsd"],"aioseo_notices":[],"episode_featured_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/03\/Stepienybarno-arata-isozaki-harvardGSD-PostDelDia-01.jpg","episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"zxGjIjp5Yy\"><a href=\"https:\/\/stepienybarno.es\/blog\/2019\/03\/11\/conferencia-de-arata-isozaki-en-harvard\/\">Conferencia de Arata Isozaki en Harvard<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2019\/03\/11\/conferencia-de-arata-isozaki-en-harvard\/embed\/#?secret=zxGjIjp5Yy\" width=\"500\" height=\"350\" title=\"\u00abConferencia de Arata Isozaki en Harvard\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"zxGjIjp5Yy\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/34713"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=34713"}],"version-history":[{"count":1,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/34713\/revisions"}],"predecessor-version":[{"id":34721,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/34713\/revisions\/34721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media\/34715"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=34713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=34713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=34713"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=34713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}