{"id":36701,"date":"2019-10-15T08:28:30","date_gmt":"2019-10-15T06:28:30","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=36701"},"modified":"2019-10-15T12:57:22","modified_gmt":"2019-10-15T10:57:22","slug":"the-black-house-proyectodeldia","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2019\/10\/15\/the-black-house-proyectodeldia\/","title":{"rendered":"The Black House #ProyectoDelD\u00eda"},"content":{"rendered":"<div id=\"attachment_36711\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/stepienybarno.es\/blog\/2019\/10\/14\/the-black-house-proyectodeldia\/stepienybarno-the-black-house-proyectodeldia-04\/\" rel=\"attachment wp-att-36711\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36711\" class=\"size-medium wp-image-36711\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-04-550x367.jpg\" alt=\"\" width=\"550\" height=\"367\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-04-550x367.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-04-180x120.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-04-1024x683.jpg 1024w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-04-316x211.jpg 316w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-04.jpg 1500w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/a><p id=\"caption-attachment-36711\" class=\"wp-caption-text\">foto: Florian Holzherr<\/p><\/div>\n<h1>Por: <a href=\"http:\/\/www.buerowagner.eu\/\" target=\"_blank\" rel=\"noopener\">Buero Wagner<\/a><\/h1>\n<h2>Fotograf\u00eda: <a href=\"http:\/\/www.florian-holzherr.com\/\" target=\"_blank\" rel=\"noopener\">Florian Holzherr<\/a><\/h2>\n<h2>Desde: <a href=\"https:\/\/www.archdaily.com\" target=\"_blank\" rel=\"noopener\">Archdaily<\/a><\/h2>\n<p><!--more--><\/p>\n<div id=\"attachment_36708\" style=\"width: 377px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/stepienybarno.es\/blog\/2019\/10\/14\/the-black-house-proyectodeldia\/stepienybarno-the-black-house-proyectodeldia-03\/\" rel=\"attachment wp-att-36708\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36708\" class=\"wp-image-36708 size-medium\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-03-367x550.jpg\" alt=\"\" width=\"367\" height=\"550\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-03-367x550.jpg 367w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-03-120x180.jpg 120w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-03-467x700.jpg 467w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-03-224x336.jpg 224w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-03-267x400.jpg 267w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-03.jpg 667w\" sizes=\"(max-width: 367px) 100vw, 367px\" \/><\/a><p id=\"caption-attachment-36708\" class=\"wp-caption-text\">foto: Florian Holzherr<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_36709\" style=\"width: 377px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/stepienybarno.es\/blog\/2019\/10\/14\/the-black-house-proyectodeldia\/stepienybarno-the-black-house-proyectodeldia-01\/\" rel=\"attachment wp-att-36709\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36709\" class=\"wp-image-36709 size-medium\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-01-367x550.jpg\" alt=\"\" width=\"367\" height=\"550\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-01-367x550.jpg 367w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-01-120x180.jpg 120w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-01-467x700.jpg 467w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-01-224x336.jpg 224w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-01-267x400.jpg 267w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-01.jpg 667w\" sizes=\"(max-width: 367px) 100vw, 367px\" \/><\/a><p id=\"caption-attachment-36709\" class=\"wp-caption-text\">foto: Florian Holzherr<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_36710\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/stepienybarno.es\/blog\/2019\/10\/14\/the-black-house-proyectodeldia\/stepienybarno-the-black-house-proyectodeldia-02\/\" rel=\"attachment wp-att-36710\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36710\" class=\"size-medium wp-image-36710\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-02-550x367.jpg\" alt=\"\" width=\"550\" height=\"367\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-02-550x367.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-02-180x120.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-02-1024x683.jpg 1024w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-02-316x211.jpg 316w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-02.jpg 1500w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/a><p id=\"caption-attachment-36710\" class=\"wp-caption-text\">foto: Florian Holzherr<\/p><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Acceder al Proyecto <a href=\"http:\/\/bit.ly\/2OMGJDc\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<h5><strong>Autores del post:\u00a0<a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a>\u00a0_ Agnieszka Stepien y Lorenzo Barn\u00f3<\/strong><\/h5>\n<h5>Y como siempre, si te gust\u00f3 el post,\u00a0estar\u00eda genial que lo compartas\u00a0en tus redes sociales.<\/h5>\n<h5>A su vez, si todav\u00eda no est\u00e1s suscrito a nuestra Newsletter, te animamos a hacerlo en la casilla que tienes al terminar este art\u00edculo.<\/h5>\n<p>&nbsp;<\/p>\n<blockquote><p>Suscribirte a nuestro blog y recibe gratis nuestra gu\u00eda: 10 Ideas para vender m\u00e1s si eres arquitecto<\/p>\n<p>Acceder:\u00a0<a href=\"http:\/\/bit.ly\/2fkkTS7\">http:\/\/bit.ly\/2fkkTS7<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Si te interesa contactar con nosotros para que te ayudemos a mejorar tu visibilidad online y, en consecuencia, mejorar tus oportunidades laborales, no dudes en escribirnos a:\u00a0<a href=\"mailto:blog@stepienybarno.es\">blog@stepienybarno.es<\/a><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">Stepienybarno en TWITTER<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">@stepienybarno (+ de 16.000 seguidores)<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno?lang=es\">https:\/\/twitter.com\/stepienybarno?lang=es<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">Stepienybarno en FACEBOOK (+ de 24<u>.000 seguidores)<\/u><\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/\">https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/<\/a><\/em><\/p>\n<p><em>Acceder a nuestro GRUPO CERRADO DE FACEBOOK sobre Identidad Digital para Arquitectos:<\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/\">https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/<\/a><\/em><\/p>\n<p><em>Suscr\u00edbete a nuestro canal de YOUTUBE:\u00a0<a href=\"http:\/\/bit.ly\/2A1UtAd\">http:\/\/bit.ly\/2A1UtAd<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>*\u00a0<a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a>\u00a0est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p>Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p>A su vez, somos socios cofundadores de\u00a0<a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a>\u00a0y directores del blog de FUNDACI\u00d3N ARQUIA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Buero Wagner Fotograf\u00eda: Florian Holzherr Desde: Archdaily<\/p>\n","protected":false},"author":10,"featured_media":36711,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[3197,244],"tags":[2143,7673,7148,7566],"series":[],"class_list":["post-36701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectodeldia","category-canal-de-arquitectura","tag-archdaily","tag-buero-wagner","tag-florian-holzherr","tag-proyectodeldia"],"aioseo_notices":[],"episode_featured_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2019\/10\/stepienybarno-the-black-house-proyectodeldia-04.jpg","episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"iB5QGoQDew\"><a href=\"https:\/\/stepienybarno.es\/blog\/2019\/10\/15\/the-black-house-proyectodeldia\/\">The Black House #ProyectoDelD\u00eda<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2019\/10\/15\/the-black-house-proyectodeldia\/embed\/#?secret=iB5QGoQDew\" width=\"500\" height=\"350\" title=\"\u00abThe Black House #ProyectoDelD\u00eda\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"iB5QGoQDew\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/36701"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=36701"}],"version-history":[{"count":4,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/36701\/revisions"}],"predecessor-version":[{"id":36734,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/36701\/revisions\/36734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media\/36711"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=36701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=36701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=36701"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=36701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}