{"id":44632,"date":"2020-11-02T08:00:37","date_gmt":"2020-11-02T06:00:37","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=44632"},"modified":"2020-10-30T18:39:12","modified_gmt":"2020-10-30T16:39:12","slug":"escuela-de-arquitectura-de-la-universidad-de-miami-proyectodeldia","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2020\/11\/02\/escuela-de-arquitectura-de-la-universidad-de-miami-proyectodeldia\/","title":{"rendered":"Escuela de Arquitectura de la Universidad de Miami #ProyectoDelD\u00eda"},"content":{"rendered":"<div id=\"attachment_44634\" style=\"width: 1592px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44634\" class=\"size-full wp-image-44634\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-1.jpg\" alt=\"\" width=\"1582\" height=\"933\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-1.jpg 1582w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-1-550x324.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-1-1024x604.jpg 1024w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-1-180x106.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-1-1536x906.jpg 1536w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-1-316x186.jpg 316w\" sizes=\"(max-width: 1582px) 100vw, 1582px\" \/><p id=\"caption-attachment-44634\" class=\"wp-caption-text\">Fotograf\u00eda: Robin Hill, Miami In Focus<\/p><\/div>\n<h1><strong>Por: Arquitectonica<br \/>\n<\/strong><\/h1>\n<h2><strong>Desde: Plataforma Arquitectura<br \/>\n<\/strong><\/h2>\n<h2><strong>Fotograf\u00eda: Robin Hill, Miami In Focus<br \/>\n<\/strong><\/h2>\n<p><!--more--><\/p>\n<div id=\"attachment_44635\" style=\"width: 1543px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44635\" class=\"size-full wp-image-44635\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-2.jpg\" alt=\"\" width=\"1533\" height=\"1000\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-2.jpg 1533w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-2-550x359.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-2-1024x668.jpg 1024w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-2-180x117.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-2-316x206.jpg 316w\" sizes=\"(max-width: 1533px) 100vw, 1533px\" \/><p id=\"caption-attachment-44635\" class=\"wp-caption-text\">Fotograf\u00eda: Robin Hill, Miami In Focus<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_44636\" style=\"width: 1592px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44636\" class=\"size-full wp-image-44636\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-3.jpg\" alt=\"\" width=\"1582\" height=\"981\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-3.jpg 1582w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-3-550x341.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-3-1024x635.jpg 1024w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-3-180x112.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-3-1536x952.jpg 1536w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-3-316x196.jpg 316w\" sizes=\"(max-width: 1582px) 100vw, 1582px\" \/><p id=\"caption-attachment-44636\" class=\"wp-caption-text\">Fotograf\u00eda: Robin Hill, Miami In Focus<\/p><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44637\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-4.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-4.jpg 1500w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-4-550x367.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-4-1024x683.jpg 1024w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-4-180x120.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-4-316x211.jpg 316w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/p>\n<p style=\"text-align: center;\">Acceder al Post <a href=\"https:\/\/bit.ly\/34GfnGh\" target=\"_blank\" rel=\"noopener noreferrer\">AQU\u00cd<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"\u00bfPara qu\u00e9 sirve un ARQUITECTO \/a? Por Jordi Ludevid\" width=\"911\" height=\"512\" src=\"https:\/\/www.youtube.com\/embed\/videoseries?list=PL9KCMehqFIajpdVXSncYV0J1ef6ms4zRx\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<hr \/>\n<h5><strong>Autores del post: <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> _ Agnieszka Stepien y Lorenzo Barn\u00f3<\/strong><\/h5>\n<h5>Y como siempre, si te gust\u00f3 el post, estar\u00eda genial que lo compartas en tus redes sociales.<\/h5>\n<h5>A su vez, si todav\u00eda no est\u00e1s suscrito a nuestra Newsletter, te animamos a hacerlo en la casilla que tienes al terminar este art\u00edculo.<\/h5>\n<p>&nbsp;<\/p>\n<blockquote><p>Suscribirte a nuestro blog y recibe gratis nuestra gu\u00eda: 10 Ideas para vender m\u00e1s si eres arquitecto<\/p>\n<p>Acceder: <a href=\"http:\/\/bit.ly\/2fkkTS7\">http:\/\/bit.ly\/2fkkTS7<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Si te interesa contactar con nosotros para que te ayudemos a mejorar tu visibilidad online y, en consecuencia, mejorar tus oportunidades laborales, no dudes en escribirnos a: <a href=\"mailto:blog@stepienybarno.es\">blog@stepienybarno.es<\/a><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">Stepienybarno en TWITTER<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">@stepienybarno (+ de 16.000 seguidores)<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno?lang=es\">https:\/\/twitter.com\/stepienybarno?lang=es<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">Stepienybarno en FACEBOOK (+ de 24<u>.000 seguidores)<\/u><\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/\">https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/<\/a><\/em><\/p>\n<p><em>Acceder a nuestro GRUPO CERRADO DE FACEBOOK sobre Identidad Digital para Arquitectos:<\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/\">https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/<\/a><\/em><\/p>\n<p><em>Suscr\u00edbete a nuestro canal de YOUTUBE: <a href=\"http:\/\/bit.ly\/2A1UtAd\">http:\/\/bit.ly\/2A1UtAd<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>* <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p>Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p>A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a> y directores del blog de FUNDACI\u00d3N ARQUIA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Arquitectonica Desde: Plataforma Arquitectura Fotograf\u00eda: Robin Hill, Miami In<\/p>\n","protected":false},"author":2,"featured_media":44635,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"audio","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[3197,244],"tags":[8428],"series":[],"class_list":["post-44632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectodeldia","category-canal-de-arquitectura","tag-arquitectonica"],"aioseo_notices":[],"episode_featured_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/10\/stepienybarno-Escuela-de-Arquitectura-de-la-Universidad-de-Miami-ProyectoDelDia-2.jpg","episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"LAB2SClSvi\"><a href=\"https:\/\/stepienybarno.es\/blog\/2020\/11\/02\/escuela-de-arquitectura-de-la-universidad-de-miami-proyectodeldia\/\">Escuela de Arquitectura de la Universidad de Miami #ProyectoDelD\u00eda<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2020\/11\/02\/escuela-de-arquitectura-de-la-universidad-de-miami-proyectodeldia\/embed\/#?secret=LAB2SClSvi\" width=\"500\" height=\"350\" title=\"\u00abEscuela de Arquitectura de la Universidad de Miami #ProyectoDelD\u00eda\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"LAB2SClSvi\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/44632"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=44632"}],"version-history":[{"count":1,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/44632\/revisions"}],"predecessor-version":[{"id":44638,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/44632\/revisions\/44638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media\/44635"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=44632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=44632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=44632"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=44632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}