{"id":50079,"date":"2021-10-22T08:02:47","date_gmt":"2021-10-22T06:02:47","guid":{"rendered":"https:\/\/stepienybarno.es\/blog\/?p=50079"},"modified":"2021-10-19T17:05:22","modified_gmt":"2021-10-19T15:05:22","slug":"la-mirada-fotografica-viajando-con-denise-para-entender-de-forma-critica-la-realidad-de-la-ciudad","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2021\/10\/22\/la-mirada-fotografica-viajando-con-denise-para-entender-de-forma-critica-la-realidad-de-la-ciudad\/","title":{"rendered":"La mirada fotogr\u00e1fica: \u201cViajando con Denise\u201d para entender de forma cr\u00edtica la realidad de la ciudad"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-50081\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2021\/10\/stepienybarno-La-mirada-fotografica-Viajando-con-Denise-para-entender-de-forma-critica-la-realidad-de-la-ciudad-Postdeldia.jpg\" alt=\"\" width=\"1024\" height=\"960\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2021\/10\/stepienybarno-La-mirada-fotografica-Viajando-con-Denise-para-entender-de-forma-critica-la-realidad-de-la-ciudad-Postdeldia.jpg 1024w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2021\/10\/stepienybarno-La-mirada-fotografica-Viajando-con-Denise-para-entender-de-forma-critica-la-realidad-de-la-ciudad-Postdeldia-550x516.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2021\/10\/stepienybarno-La-mirada-fotografica-Viajando-con-Denise-para-entender-de-forma-critica-la-realidad-de-la-ciudad-Postdeldia-747x700.jpg 747w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2021\/10\/stepienybarno-La-mirada-fotografica-Viajando-con-Denise-para-entender-de-forma-critica-la-realidad-de-la-ciudad-Postdeldia-180x169.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2021\/10\/stepienybarno-La-mirada-fotografica-Viajando-con-Denise-para-entender-de-forma-critica-la-realidad-de-la-ciudad-Postdeldia-316x296.jpg 316w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h1><strong>Por: mayorga+fontana<br \/>\n<\/strong><\/h1>\n<h2>Desde: veredes, arquitectura y divulgaci\u00f3n<\/h2>\n<h2>Fotograf\u00eda: Relaciones entre las figuras humanas, la arquitectura y el espacio urbano a trav\u00e9s de la fotograf\u00eda como mirada cr\u00edtica: Las Vegas and Denise Style, Bob Style and Magritte Stye. Juegos de escala manieristas. Fotograf\u00edas: Robert Venturi y Denise Scott Brown, 1966<\/h2>\n<p>El urbanismo en los a\u00f1os 60 hab\u00eda entrado en un periodo de crisis. En Estados Unidos los proyectos de renovaci\u00f3n urbana de gran escala, pusieron en duda aquella aproximaci\u00f3n que promet\u00eda una mejor ciudad futura que superar\u00eda la existente. Arquitectos y planificadores se dieron a la tarea de promover la ciudad del autom\u00f3vil, una ciudad en explosi\u00f3n, descentralizada y configurada por suburbios. Los debates desde las escuelas de arquitectura y arte, asum\u00edan la mirada a esa ciudad en transformaci\u00f3n y se planteaba, a la vez, un tema central sobre como hacer visible de forma cr\u00edtica \u201cla imagen de la ciudad\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/bit.ly\/3B7tnGp\" target=\"_blank\" rel=\"noopener noreferrer\">Acceder al post<\/a><\/p>\n<hr \/>\n<h5><strong>Autores del post: <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> _ Agnieszka Stepien y Lorenzo Barn\u00f3<\/strong><\/h5>\n<h5>Y como siempre, si te gust\u00f3 el post, estar\u00eda genial que lo compartas en tus redes sociales.<\/h5>\n<h5>A su vez, si todav\u00eda no est\u00e1s suscrito a nuestra Newsletter, te animamos a hacerlo en la casilla que tienes al terminar este art\u00edculo.<\/h5>\n<p>&nbsp;<\/p>\n<p>Suscribirte a nuestro blog y recibe gratis nuestra gu\u00eda: 10 Ideas para vender m\u00e1s si eres arquitecto<\/p>\n<p>Acceder: <a href=\"http:\/\/bit.ly\/2fkkTS7\">http:\/\/bit.ly\/2fkkTS7<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Si te interesa contactar con nosotros para que te ayudemos a mejorar tu visibilidad online y, en consecuencia, mejorar tus oportunidades laborales, no dudes en escribirnos a: <a href=\"mailto:blog@stepienybarno.es\">blog@stepienybarno.es<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">Stepienybarno en TWITTER<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">@stepienybarno (+ de 16.000 seguidores)<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno?lang=es\">https:\/\/twitter.com\/stepienybarno?lang=es<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">Stepienybarno en FACEBOOK (+ de 24<u>.000 seguidores)<\/u><\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/\">https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/<\/a><\/em><\/p>\n<p><em>Acceder a nuestro GRUPO CERRADO DE FACEBOOK sobre Identidad Digital para Arquitectos:<\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/\">https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/<\/a><\/em><\/p>\n<p><em>Suscr\u00edbete a nuestro canal de YOUTUBE: <a href=\"http:\/\/bit.ly\/2A1UtAd\">http:\/\/bit.ly\/2A1UtAd<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>* <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p>Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p>A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a> y directores del blog de FUNDACI\u00d3N ARQUIA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: mayorga+fontana Desde: veredes, arquitectura y divulgaci\u00f3n Fotograf\u00eda: Relaciones entre<\/p>\n","protected":false},"author":2,"featured_media":50081,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"audio","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[244],"tags":[8958],"series":[],"class_list":["post-50079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canal-de-arquitectura","tag-mayorgafontana"],"aioseo_notices":[],"episode_featured_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2021\/10\/stepienybarno-La-mirada-fotografica-Viajando-con-Denise-para-entender-de-forma-critica-la-realidad-de-la-ciudad-Postdeldia.jpg","episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"VhsgtinHlf\"><a href=\"https:\/\/stepienybarno.es\/blog\/2021\/10\/22\/la-mirada-fotografica-viajando-con-denise-para-entender-de-forma-critica-la-realidad-de-la-ciudad\/\">La mirada fotogr\u00e1fica: \u201cViajando con Denise\u201d para entender de forma cr\u00edtica la realidad de la ciudad<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2021\/10\/22\/la-mirada-fotografica-viajando-con-denise-para-entender-de-forma-critica-la-realidad-de-la-ciudad\/embed\/#?secret=VhsgtinHlf\" width=\"500\" height=\"350\" title=\"\u00abLa mirada fotogr\u00e1fica: \u201cViajando con Denise\u201d para entender de forma cr\u00edtica la realidad de la ciudad\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"VhsgtinHlf\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/50079"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=50079"}],"version-history":[{"count":2,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/50079\/revisions"}],"predecessor-version":[{"id":50082,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/50079\/revisions\/50082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media\/50081"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=50079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=50079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=50079"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=50079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}