{"id":5104,"date":"2012-02-14T09:51:28","date_gmt":"2012-02-14T07:51:28","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=5104"},"modified":"2012-02-14T09:51:28","modified_gmt":"2012-02-14T07:51:28","slug":"aniversario-de-la-muerte-de-alejandro-de-la-sota","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2012\/02\/14\/aniversario-de-la-muerte-de-alejandro-de-la-sota\/","title":{"rendered":"ANIVERSARIO DE LA MUERTE DE ALEJANDRO DE LA SOTA."},"content":{"rendered":"<p align=\"left\">\n<p align=\"left\">\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5105\" title=\"alejandro-de-la-sota en stepienybarno\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/02\/alejandro-de-la-sota-en-stepienybarno.jpg\" alt=\"alejandro-de-la-sota en stepienybarno\" width=\"300\" height=\"296\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/02\/alejandro-de-la-sota-en-stepienybarno.jpg 300w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/02\/alejandro-de-la-sota-en-stepienybarno-180x178.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p align=\"left\">\n<p align=\"left\">Tal d\u00eda como hoy de 1996 muri\u00f3 este gran arquitecto. Para conmemorar tal d\u00eda, nos atrevemos a traer, a nuestra publicaci\u00f3n, extractos del texto que Josep Quetglas escribi\u00f3 en su homenaje.<\/p>\n<p align=\"left\"><!--more--><\/p>\n<p align=\"left\">\n<p align=\"left\">\u201cMe encuentro en una situaci\u00f3n inc\u00f3moda.<br \/>\nPor un lado, me enorgullece y agradezco poder estar aqu\u00ed, poder tomar parte en esta ceremonia de la Escuela de arquitectura de Madrid en memoria de Alejandro de la Sota.\u201d<\/p>\n<p align=\"left\">\n<p align=\"left\">\u201cEste acto ya tendr\u00eda sentido si en nuestra reuni\u00f3n nadie hablara, si ocurriera un silencio suficientemente atento como para presenciar y enmarcar el silencio que, desde ahora, ser\u00e1 el de Alejandro de la Sota.\u201d<\/p>\n<p align=\"left\">\n<p align=\"left\">\u201c\u00bfMuerto es lo que no est\u00e1 en vida? \u00bfQue est\u00e9 muerto significa que ya no est\u00e1 vivo?<br \/>\nNo exactamente.<br \/>\nMuerto es lo que ya no puede vivir por s\u00ed mismo, lo que, de seguir siendo tiempo vivo, requiere del apoyo en otros.\u201d<\/p>\n<p align=\"left\">\n<p align=\"left\">\u201c- Recuerdo ahora dos frases, le\u00eddas en autores dispares.<br \/>\nUna es un verso de Borges. \u00abSomos los que se van\u00bb. Escrito de otro modo, en un poema posterior, resultaba: \u00abS\u00f3lo el que ha muerto es nuestro\u00bb.<br \/>\nLa otra frase es de un ensayo de John Berger: \u00abLos muertos son la imaginaci\u00f3n de los vivos\u00bb.<br \/>\nAmbas frases me resultan enigm\u00e1ticas, porque no encuentro modo de determinar el sujeto y el objeto que quedan a lado y lado del verbo \u00abser\u00bb. \u201c<\/p>\n<p align=\"left\">\n<p align=\"left\">\n<p align=\"left\">\n<p align=\"left\"><a href=\"http:\/\/www.hicarquitectura.com\/2009\/10\/que-decir-palabras-para-alejandro-de-la_9287.html\">Acceder a la noticia<\/a><\/p>\n<p align=\"left\">\n<p align=\"left\">Noticia seleccionada por el Canal de arquitectura STEPIENYBARNO.<\/p>\n<p align=\"left\"><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\">STEPIENYBARNO EN LINKEDIN<\/a><\/p>\n<p align=\"left\"><a href=\"http:\/\/twitter.com\/stepienybarno\/stepienybarno\">STEPIENYBARNO EN TWITTER<\/a><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.facebook.com\/StepienybarnoCANAL\">STEPIENYBARNO EN FACEBOOK<\/a><\/p>\n<p align=\"left\">\n<p align=\"left\">*Stepienybarno est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p align=\"left\">Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n (comunicaci\u00f3n y difusi\u00f3n) y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p align=\"left\">A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a> y redactores de <a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\">LA CIUDAD VIVA<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tal d\u00eda como hoy de 1996 muri\u00f3 este gran arquitecto. Para conmemorar tal d\u00eda, nos atrevemos a traer, a nuestra publicaci\u00f3n, extractos del texto que Josep Quetglas escribi\u00f3 en su homenaje.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[34,4,244],"tags":[4274,598,9,608],"series":[],"class_list":["post-5104","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-arquilectura","category-canal-de-arquitectura","tag-actualidad","tag-alejandro-de-la-sota","tag-arquitectura","tag-josep-quetglas"],"aioseo_notices":[],"episode_featured_image":false,"episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"1qR8S7q4Yg\"><a href=\"https:\/\/stepienybarno.es\/blog\/2012\/02\/14\/aniversario-de-la-muerte-de-alejandro-de-la-sota\/\">ANIVERSARIO DE LA MUERTE DE ALEJANDRO DE LA SOTA.<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2012\/02\/14\/aniversario-de-la-muerte-de-alejandro-de-la-sota\/embed\/#?secret=1qR8S7q4Yg\" width=\"500\" height=\"350\" title=\"\u00abANIVERSARIO DE LA MUERTE DE ALEJANDRO DE LA SOTA.\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"1qR8S7q4Yg\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/5104"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=5104"}],"version-history":[{"count":2,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/5104\/revisions"}],"predecessor-version":[{"id":5107,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/5104\/revisions\/5107"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=5104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=5104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=5104"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=5104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}