{"id":5163,"date":"2012-02-24T11:06:22","date_gmt":"2012-02-24T09:06:22","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=5163"},"modified":"2012-02-24T11:06:22","modified_gmt":"2012-02-24T09:06:22","slug":"entrevista-a-benjamin-nahoum_-parte-1-cooperativas-de-vivienda-en-uruguay-2","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2012\/02\/24\/entrevista-a-benjamin-nahoum_-parte-1-cooperativas-de-vivienda-en-uruguay-2\/","title":{"rendered":"ENTREVISTA A BENJAM\u00cdN NAHOUM_ Parte 1. Cooperativas de vivienda en Uruguay #2"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5164\" title=\"SYB benjamin y raul jardin ETSAG oct2011\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/02\/SYB-benjamin-y-raul-jardin-ETSAG-oct2011-350x250.jpg\" alt=\"SYB benjamin y raul jardin ETSAG oct2011\" width=\"350\" height=\"250\" \/><\/p>\n<p><span style=\"color: #888888;\">Benjam\u00edn Naohum y Ra\u00fal Vall\u00e9s. ETSA Granada, octubre de 2011. Fuente: Fiore + Eva<\/span><\/p>\n<p>En esta segunda entrega de la serie de art\u00edculos sobre el cooperativismo de vivienda uruguayo, nos vamos al encuentro de Benjam\u00edn Nahoum, Ingeniero Civil, docente e investigador uruguayo, al que tuvimos la suerte de entrevistar en su \u00faltima visita a Granada el pasado octubre [1].<\/p>\n<p><!--more--><\/p>\n<p>Ante la imposibilidad de resumir su extenso curr\u00edculo en unas pocas l\u00edneas, apuntamos s\u00f3lo algunas pinceladas:<\/p>\n<p>&#8211;\u00a0 Investigaciones sobre vivienda, como parte del equipo de \u201cEvaluaci\u00f3n de programas y Tecnolog\u00edas para la vivienda de inter\u00e9s social\u201d del Instituto de la Construcci\u00f3n de la <a href=\"http:\/\/www.farq.edu.uy\/\">Facultad de Arquitectura<\/a>, Universidad de la Rep\u00fablica uruguaya y tambi\u00e9n como investigador independiente;<\/p>\n<p>&#8211;\u00a0 Redactor Responsable e integrante del Comit\u00e9 Editor de la <a href=\"http:\/\/www.farq.edu.uy\/publicaciones\/viviendapopular.html\">revista \u201cVivienda Popular\u201d;<\/a><\/p>\n<p><a href=\"http:\/\/www.farq.edu.uy\/publicaciones\/viviendapopular.html\">&#8211;\u00a0 Ex Coordinador d<\/a>el Sector Vivienda del Centro Cooperativista Uruguayo;<\/p>\n<p>&#8211;\u00a0 Asesor en pol\u00edticas y planes urbanos en el desarrollo de vivienda desde la Intendencia Municipal de Montevideo (la alcald\u00eda de la capital uruguaya);<\/p>\n<p>&#8211;\u00a0 Coordinador del equipo interdisciplinario para la creaci\u00f3n de la \u2018Cartera de Inmuebles para Vivienda de Inter\u00e9s Social\u2019 del Ministerio de Vivienda Ordenamiento Territorial y Medio Ambiente de Uruguay.<\/p>\n<p>&#8211;\u00a0 Responsable T\u00e9cnico del Departamento de Apoyo T\u00e9cnico de la Federaci\u00f3n Uruguaya de Cooperativas de Vivienda por Ayuda Mutua (FUCVAM).<\/p>\n<p>&#8211;\u00a0 Asesor de Proyectos de Ley de Vivienda Popular en Paraguay, Bolivia, Honduras, Guatemala, Nicaragua y El Salvador, en el marco del \u2018Programa Regional de Vivienda y H\u00e1bitat FUCVAM-Centro Cooperativa Sueco\u2019,<\/p>\n<p>Agradecemos enormemente a Benjam\u00edn Nahoum su total disponibilidad y esfuerzo en la difusi\u00f3n de las buenas pr\u00e1cticas en la producci\u00f3n y gesti\u00f3n social del h\u00e1bitat, en cuyo desarrollo ha participado desde los comienzos de su actividad profesional, as\u00ed como a nuestros amigos de Stepienybarno por la c\u00e1lida acogida a nuestra propuesta de publicaci\u00f3n de esta entrevista, conjuntamente con el blog de La Ciudad Viva.<\/p>\n<p>En esta primera parte<strong> <\/strong>de la entrevista, su protagonista nos habla de su vinculaci\u00f3n original y actual con el cooperativismo de vivienda, as\u00ed como de aspectos esenciales para la comprensi\u00f3n de esta manera de construir h\u00e1bitat social, como son el \u201cModelo FUCVAM\u201d y las Carteras de Tierras.\u00a0En el blog de La Ciudad Viva, encontrar\u00e9is la segunda parte, en la que nos centramos en la puesta en pr\u00e1ctica de las cooperativas de vivienda, comentando cuestiones como su creaci\u00f3n, el proceso de capacitaci\u00f3n de los participantes, en qu\u00e9 consiste la ayuda mutua y las t\u00e9cnicas constructivas y materiales m\u00e1s empleados, terminando con una reflexi\u00f3n sobre las dificultades y las oportunidades de implantaci\u00f3n de un modelo similar en Espa\u00f1a.<\/p>\n<p>Comenzamos&#8230;<\/p>\n<p>&#8211; Benjam\u00edn, nos interesa conocer por un lado tu trayectoria personal y por otro c\u00f3mo llegaste a incorporarte en el tema de las cooperativas.<\/p>\n<p>&#8211; Bueno, yo soy Ingeniero Civil, y cuando, reci\u00e9n recibido, empec\u00e9 a buscar trabajo lo encontr\u00e9 en un instituto de asesoramiento t\u00e9cnico (lo que en Uruguay llamamos IAT) que estaba desarrollando una experiencia con las cooperativas de ayuda mutua en mi pa\u00eds y, bueno, empec\u00e9 a trabajar all\u00ed, y fue ah\u00ed que descubr\u00ed el cooperativismo. Porque, la verdad, en la Universidad nadie me hab\u00eda hablado de las cooperativas.<\/p>\n<p>&#8211; \u00bfDe qu\u00e9 a\u00f1o estamos hablando?<\/p>\n<p>&#8211; De 1972. Ya, en aquel momento, el cooperativismo ten\u00eda tres a\u00f1os de existencia y se estaban construyendo muchas viviendas y fij\u00e1os, la Universidad como si nada. Esa situaci\u00f3n de que la Academia va por un lado, y la gente haciendo cosas va por otro, lamentablemente no ha cambiado.<\/p>\n<p>&#8211; \u00bfEn todo este tiempo?<\/p>\n<p>&#8211; Pues no: no ha cambiado. Estamos haciendo ahora con el amigo Ra\u00fal Vall\u00e9s y otros compa\u00f1eros de las Facultades de Arquitectura y Ciencias Sociales de la Universidad de la Rep\u00fablica, todo lo posible para que s\u00ed cambie. Pero la realidad es -todav\u00eda- que el tema del cooperativismo y el tema del h\u00e1bitat social no forman parte en el Uruguay de las carreras de grado, salvo como menciones en otros cursos.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5165\" title=\"SYB benjamin charla ETSAG oct2011\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/02\/SYB-benjamin-charla-ETSAG-oct2011-350x214.jpg\" alt=\"SYB benjamin charla ETSAG oct2011\" width=\"350\" height=\"214\" \/><br \/>\n<span style=\"color: #888888;\">Charla Benjam\u00edn Nahoum y Ra\u00fal Vall\u00e9s, ETSA Granada, octubre 2011. Fuente: Fiore + Eva<\/span><\/p>\n<p>&#8211; Antes de centrarnos en el \u201cModelo FUCVAM\u201d, nos gustar\u00eda conocer c\u00f3mo se produce el nacimiento de una cooperativa. \u00bfC\u00f3mo se asocia la gente? \u00bfAcuden a alguna entidad para asesorarse y decidir qu\u00e9 modelo de cooperativa es m\u00e1s adecuado en su caso?<\/p>\n<p>&#8211; Hay diferentes caminos: en este momento, el m\u00e1s transitado pasa por <a href=\"http:\/\/www.fucvam.org.uy\/\">FUCVAM<strong>, la <\/strong><\/a>Federaci\u00f3n Uruguaya de Cooperativas de Vivienda por Ayuda Mutua. En algunos casos la inquietud es individual, y lo que le interesa a la familia es ingresar en una cooperativa que ya est\u00e1 formada. En otros casos, se re\u00fane un grupo de personas: por ejemplo, en el lugar de trabajo, en el sindicato, en un club deportivo, personas que llevan a sus ni\u00f1os a la misma escuela, y mientras esperan que salga el ni\u00f1o se ponen a conversar y se encuentran que tienen el mismo problema. Y lo que hacen es acudir a FUCVAM para informarse qu\u00e9 pasos tienen que dar. En FUCVAM se les da informaci\u00f3n, se les explica c\u00f3mo es el sistema, qu\u00e9 es lo que tienen que hacer, cu\u00e1les son las posibilidades, las caracter\u00edsticas, y, en el caso de que la gente est\u00e9 interesada en formar una cooperativa, se les da apoyo para hacerlo a trav\u00e9s de estatutos-tipo, asistencia notarial, asistencia social&#8230; una serie de cosas que, en ese momento inicial, ayudan a la gente a formar la cooperativa, hasta que, ya formada, contrata su propio equipo t\u00e9cnico.<\/p>\n<p>&#8211; El servicio que da FUCVAM, \u00bflo hace desde una oficina propia o alojada en la administraci\u00f3n p\u00fablica? Porque el servicio que da se asemeja a una asistencia social&#8230;<\/p>\n<p>&#8211; FUCVAM tiene su sede central en Montevideo, y adem\u00e1s tiene en cada departamento, (los departamentos son el equivalente a lo que ser\u00edan las provincias en otros pa\u00edses) una Mesa Departamental. Es todo un sistema descentralizado, territorializado, y entonces la gente acude al contacto de su localidad. Si es en Montevideo, a la Sede Central, y si es en un departamento del interior, pues a la Mesa Departamental. Las cosas m\u00e1s especializadas, como el tema notarial, por ejemplo, se hacen en la Sede Central. Pero todo lo que es brindar informaci\u00f3n, explicar, los primeros pasos, se hace desde el lugar donde se forma cada cooperativa.<\/p>\n<p>&#8211; \u00bfEn qu\u00e9 momento surge FUCVAM? \u00bfEs en los comienzos de las cooperativas o es algo a lo que se llega con posterioridad?<\/p>\n<p>-El sistema cooperativo en Uruguay se inicia en 1966 con tres experiencias piloto de vivienda, con el apoyo de una ONG, el Centro Cooperativista Uruguayo (CCU). Y ah\u00ed es realmente donde nacen las cooperativas. Y nacen sobre una base que es la que corresponde al modelo FUCVAM, o sea, cooperativas de ayuda mutua y propiedad colectiva. Despu\u00e9s, la Ley, admitir\u00e1 otras modalidades: que el aporte de los interesados, en vez de ser en trabajo, en ayuda mutua, pueda ser en ahorro, y as\u00ed se forman las cooperativas de ahorro previo; y tambi\u00e9n la opci\u00f3n de que la propiedad, en vez de colectiva sea individual. O sea, que hay en realidad varias modalidades de cooperativas, pero lo que llamamos el \u201cModelo FUCVAM\u201d nosotros, porque las cooperativas de ayuda mutua y propiedad colectiva est\u00e1n asociadas a FUCVAM, corresponde a esa variante.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5166\" title=\"Cierre Ciudad Vieja 2011-2\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/02\/Cierre-Ciudad-Vieja-2011-2-350x226.jpg\" alt=\"Cierre Ciudad Vieja 2011-2\" width=\"350\" height=\"226\" \/><\/p>\n<p><span style=\"color: #888888;\">Manifestaci\u00f3n FUCVAM en la Ciudad Vieja de Montevideo (2011). Fuente: Benjam\u00edn Nahoum<\/span><\/p>\n<p>&#8211; \u00bfPodemos decir entonces que el \u201cModelo FUCVAM\u201d es el modelo original de cooperativa, el que surge en un principio?<\/p>\n<p>&#8211; Exactamente, es el modelo con el cual se hicieron las experiencias piloto. Despu\u00e9s, la Ley Nacional de Vivienda cre\u00f3 otras modalidades distintas, pero las cooperativas surgen con ese modelo.<\/p>\n<p>&#8211; Las cooperativas acceden al terreno a trav\u00e9s de la \u201cCartera\u201d o Banco de Tierras\u2019 del Estado, \u00bfc\u00f3mo surge esta figura?<\/p>\n<p>&#8211; Surge como respuesta a una necesidad. En el sistema cooperativo, las cooperativas pueden obtener un pr\u00e9stamo del Estado para financiar la construcci\u00f3n de sus viviendas. Este pr\u00e9stamo incluye el precio del terreno, as\u00ed que te\u00f3ricamente estar\u00eda solucionado el acceso al suelo. Pero el problema es que, para pedir el pr\u00e9stamo, necesitas tener un terreno, porque tienes que hacer un proyecto y tienes que hacer un presupuesto, y obviamente eso no se puede hacer si no tienes un terreno.<\/p>\n<p>As\u00ed que es como una especie de c\u00edrculo vicioso: puedo acceder al terreno si consigo el pr\u00e9stamo, pero para solicitar el pr\u00e9stamo tengo que tener el terreno. Ese c\u00edrculo se rompe justamente a trav\u00e9s de la Cartera de Tierras. Si el Estado le adjudica a la cooperativa un terreno, la cooperativa est\u00e1 en condiciones de iniciar toda la gesti\u00f3n, y lo \u00fanico que hace falta es que pague en el momento que obtiene el cr\u00e9dito. Y el Estado la espera, cosa que no hacen los propietarios privados de suelo.<\/p>\n<p>Esa es la idea de la Cartera: el terreno se adjudica, la cooperativa puede hacer toda su gesti\u00f3n y paga, (y, obviamente, recibe la propiedad del terreno) en el momento en que, ya con el pr\u00e9stamo, est\u00e1 en condiciones de pagar. As\u00ed funcion\u00f3 en los primeros a\u00f1os de la Ley Nacional de Vivienda, despu\u00e9s tuvimos una dictadura, mucho liberalismo en materia econ\u00f3mica y la Cartera desapareci\u00f3, dej\u00f3 de funcionar, porque se apostaba al Mercado, hasta 1990, cuando un gobierno de izquierdas accede a la alcald\u00eda de Montevideo. Pero reci\u00e9n a partir de 2008, volvemos a tener una Cartera de Tierras a nivel nacional, es decir, no de Montevideo, sino de todo el pa\u00eds.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5167\" title=\"Afiche-Foro-FUCVAM-749x1024\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/02\/Afiche-Foro-FUCVAM-749x1024.jpeg\" alt=\"Afiche-Foro-FUCVAM-749x1024\" width=\"469\" height=\"640\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/02\/Afiche-Foro-FUCVAM-749x1024.jpeg 469w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/02\/Afiche-Foro-FUCVAM-749x1024-132x180.jpeg 132w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/02\/Afiche-Foro-FUCVAM-749x1024-403x550.jpeg 403w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/02\/Afiche-Foro-FUCVAM-749x1024-293x400.jpeg 293w\" sizes=\"(max-width: 469px) 100vw, 469px\" \/><\/p>\n<p>&#8211; Sabemos que en estos \u00faltimos a\u00f1os, especialmente t\u00fa junto con otra gente, est\u00e1is tratando de transferir el modelo a otros pa\u00edses en Latinoam\u00e9rica. Quisi\u00e9ramos que nos contaras c\u00f3mo surge la idea de llevar el modelo de las cooperativas a otros pa\u00edses y\u2026 \u00bfen qu\u00e9 momento se encuentran ahora?<\/p>\n<p>&#8211; La intenci\u00f3n de difundir este modelo, est\u00e1 pr\u00e1cticamente desde el comienzo, porque tenemos un convencimiento muy fuerte de sus virtudes, de que es realmente la mejor alternativa posible para los sectores populares.<\/p>\n<p>En los \u00faltimos a\u00f1os FUCVAM, en particular, ha desarrollado una acci\u00f3n sistem\u00e1tica en este sentido, fundamentalmente en Am\u00e9rica Latina, con el apoyo del <a href=\"http:\/\/www.sccportal.org\/Inicio.aspx\">Centro Cooperativo Sueco<\/a>. En su tesis de maestr\u00eda sobre cooperaci\u00f3n, una compatriota de ustedes que anduvo bastante tiempo por Uruguay, la amiga Marta Solanas, ha caracterizado muy bien esto como un <em>\u2018ejemplo de cooperaci\u00f3n Sur-Sur\u2019<\/em>, o sea, de cooperaci\u00f3n que no es de apoyo econ\u00f3mico sino de transferencia de conocimiento, de tecnolog\u00eda blanda. Para poder hacerlo, ah\u00ed s\u00ed, se cont\u00f3 con la cooperaci\u00f3n econ\u00f3mica y log\u00edstica del Centro Cooperativo Sueco, porque evidentemente este tipo de cosas tienen un costo, hay que ir a los lugares, recibir pasant\u00edas, en fin el intercambio implica viajes y los viajes cuestan dinero.<\/p>\n<p>Lo que se procura con esto es difundir el modelo en la regi\u00f3n, y por ello hemos trabajado en Bolivia, en Paraguay, en Brasil, en Argentina, y en Centroam\u00e9rica, en El Salvador, Nicaragua, Honduras y Guatemala, con mucha intensidad y en otros pa\u00edses con contactos m\u00e1s puntuales.<\/p>\n<p>En todos estos lugares la idea del trabajo ha sido, primero que nada, difundir la idea, hacer conocer bien el modelo, y en la medida que encontramos receptividad -que la hemos encontrado en todos los casos- ayudar a hacer experiencias piloto, y a que la gente se organice, a que trate de encaminar sus esfuerzos a trav\u00e9s de este modelo.<\/p>\n<p>Y bueno, despu\u00e9s vienen los pasos que dec\u00edamos son necesarios para Espa\u00f1a, para Uruguay y para cualquier pa\u00eds, que son el marco legal, el marco financiero\u2026 As\u00ed es como, en todos esos lugares que mencion\u00e9, ya hay experiencias terminadas; y en varios, ya hay leyes que admiten un modelo cooperativo y que tienen alg\u00fan canal de financiamiento para hacerlo posible. Todav\u00eda queda mucho por avanzar, pero hay un camino emprendido, con vigor, con muy buena receptividad, y adem\u00e1s -lo que podr\u00eda ser sorprendente a primera vista-, muy buena aceptaci\u00f3n del modelo de la propiedad colectiva, que tan lejos est\u00e1 de los paradigmas de la sociedad individualista actual.<\/p>\n<p>&#8211; \u00bfCu\u00e1nto tiempo hace que est\u00e1is con esta labor de difusi\u00f3n?<\/p>\n<p>&#8211; Pr\u00e1cticamente se empez\u00f3 a finales de los a\u00f1os 90, con experiencias en los pa\u00edses m\u00e1s cercanos, fundamentalmente en Brasil, en Paraguay, y ahora hemos llegado a todos los pa\u00edses que mencion\u00e9. Por supuesto, hay contactos en otros lugares: en Cuba, Hait\u00ed, Per\u00fa, en algunos pa\u00edses de \u00c1frica&#8230; La idea es que all\u00e1 donde alguien se interesa por esto, tratamos de llegar de alguna manera.<\/p>\n<p>&#8211; \u00bfY en el caso espa\u00f1ol? \u00bfTenemos esperanza de que realmente pueda desarrollarse aqu\u00ed?<\/p>\n<p>&#8211; En Espa\u00f1a hemos encontrado mucha receptividad, mucho inter\u00e9s, a nivel de la Universidad, pero no hemos tenido la posibilidad todav\u00eda de tener contacto con organizaciones sociales, que es una cosa muy importante, porque en definitiva, este tipo de cosas las saca adelante la gente. Pero no descartamos que en alg\u00fan momento tambi\u00e9n podamos en pa\u00edses de Europa y de otros lugares, ayudar, de alguna manera, a transmitir una idea, un modelo, que obviamente no es para ser calcado: hay que adaptarlo a cada lugar, por supuesto, pero hay una serie de cosas que son un poco las bases: la propiedad colectiva, la autogesti\u00f3n, la ayuda mutua, la participaci\u00f3n, que son los puntos neur\u00e1lgicos para desarrollar este modelo.<\/p>\n<p>Y hasta aqu\u00ed la primera parte de la entrevista. Continuamos con la segunda parte en el blog de La Ciudad Viva.<\/p>\n<p><em>Fiorella Russo + Eva Chac\u00f3n<\/em><\/p>\n<p><em> <\/em><\/p>\n<p>Notas:<\/p>\n<p>[1] Visita a Granada realizada junto al Arquitecto Ra\u00fal Vall\u00e9s, con objeto de impartir las conferencias: <em>\u2018La producci\u00f3n Social del H\u00e1bitat: un desaf\u00edo para la arquitectura y la interdisciplina. La experiencia uruguaya del cooperativismo de viviendas\u2019<\/em> (25 de octubre, Colegio Oficial de Arquitectos de Granada) y <em>\u2018La ciudad que hace la gente: autoproducci\u00f3n individual y colectiva, vivienda cooperativismo y ciudadan\u00eda\u2019 <\/em>(26 de octubre de 2011, ETS Arquitectura \u2013 Departamento de Urbanismo y Ordenaci\u00f3n del Territorio, Universidad de Granada).<\/p>\n<p>* Este art\u00edculo ha sido escrito con car\u00e1cter divulgativo y sin ning\u00fan tipo de \u00e1nimo de lucro. As\u00ed que si te apetece compartirlo en cualquier otro medio, estaremos encantados de que lo hagas siempre y cuando cites el lugar donde lo has encontrado.<\/p>\n<p>* Fiorella Russo es arquitecta e investigadora en el Departamento de Urbanismo y Ordenaci\u00f3n del Territorio de la Universidad de Granada y en la International Network for Urban Research and Action [INURA]. Es miembro activa de ADOBE \u2018Arquitectura y Compromiso Social\u2019.<\/p>\n<p>* Eva Chac\u00f3n es arquitecta, docente e investigadora en el Departamento de Construcciones Arquitect\u00f3nicas de la Universidad de Granada y coordinadora del Proyecto I+D+i Reciclajes Urbanos, dirigido por Elisa Valero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta segunda entrega de la serie de art\u00edculos sobre el cooperativismo de vivienda uruguayo, nos vamos al encuentro de Benjam\u00edn Nahoum, Ingeniero Civil, docente e investigador uruguayo, al que tuvimos la suerte de entrevistar en su \u00faltima visita a Granada el pasado octubre [1].<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[63],"tags":[43,24,331,1506],"series":[],"class_list":["post-5163","post","type-post","status-publish","format-standard","hentry","category-arqui-entrevista","tag-arquitectura-latinoamericana","tag-entrevista","tag-vivienda","tag-vivienda-social"],"aioseo_notices":[],"episode_featured_image":false,"episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"RJG7ut2Zyj\"><a href=\"https:\/\/stepienybarno.es\/blog\/2012\/02\/24\/entrevista-a-benjamin-nahoum_-parte-1-cooperativas-de-vivienda-en-uruguay-2\/\">ENTREVISTA A BENJAM\u00cdN NAHOUM_ Parte 1. Cooperativas de vivienda en Uruguay #2<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2012\/02\/24\/entrevista-a-benjamin-nahoum_-parte-1-cooperativas-de-vivienda-en-uruguay-2\/embed\/#?secret=RJG7ut2Zyj\" width=\"500\" height=\"350\" title=\"\u00abENTREVISTA A BENJAM\u00cdN NAHOUM_ Parte 1. Cooperativas de vivienda en Uruguay #2\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"RJG7ut2Zyj\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/5163"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=5163"}],"version-history":[{"count":2,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/5163\/revisions"}],"predecessor-version":[{"id":5169,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/5163\/revisions\/5169"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=5163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=5163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=5163"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=5163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}