{"id":52193,"date":"2022-03-01T08:01:49","date_gmt":"2022-03-01T06:01:49","guid":{"rendered":"https:\/\/stepienybarno.es\/blog\/?p=52193"},"modified":"2022-02-24T21:21:07","modified_gmt":"2022-02-24T19:21:07","slug":"las-piedras-de-santa-maria-del-mar-hablan","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2022\/03\/01\/las-piedras-de-santa-maria-del-mar-hablan\/","title":{"rendered":"Las piedras de Santa Maria del Mar hablan"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-52194\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/02\/stepienybarno-Las-piedras-de-Santa-Maria-del-Mar-hablan-Postdeldia.jpg\" alt=\"\" width=\"1960\" height=\"1316\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/02\/stepienybarno-Las-piedras-de-Santa-Maria-del-Mar-hablan-Postdeldia.jpg 1960w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/02\/stepienybarno-Las-piedras-de-Santa-Maria-del-Mar-hablan-Postdeldia-550x369.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/02\/stepienybarno-Las-piedras-de-Santa-Maria-del-Mar-hablan-Postdeldia-1024x688.jpg 1024w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/02\/stepienybarno-Las-piedras-de-Santa-Maria-del-Mar-hablan-Postdeldia-180x121.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/02\/stepienybarno-Las-piedras-de-Santa-Maria-del-Mar-hablan-Postdeldia-1536x1031.jpg 1536w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/02\/stepienybarno-Las-piedras-de-Santa-Maria-del-Mar-hablan-Postdeldia-316x212.jpg 316w\" sizes=\"(max-width: 1960px) 100vw, 1960px\" \/><\/p>\n<h1><strong>Por: Jos\u00e9 \u00c1ngel Monta\u00f1\u00e9s<br \/>\n<\/strong><\/h1>\n<h2>Desde: <strong>El Pa\u00eds<br \/>\n<\/strong><\/h2>\n<h2>Fotograf\u00eda: Fachada principal de Santa Maria del Mar, con el roset\u00f3n y las dos torres en la que se aprecian los agujeros de los mechinales donde se instalaron las plataformas para construirla.Joan Sanchez (EL PA\u00cdS).<\/h2>\n<p>Uno de los programas de mayor \u00e9xito en la televisi\u00f3n espa\u00f1ola en los setenta fue Si las piedras hablaran; un paseo por un monumento en el que una voz en off explicaba en primera persona su historia a partir de guiones de Antonio Gala y presentaci\u00f3n de Natalia Figueroa. Los edificios, por desgracia, no hablan, pero hay personas capaces de leer lo que cuentan sus piedras. Como el ge\u00f3logo y profesor M\u00e0rius Vendrell, que desde 2017 tiene puesta su mirada en uno de los edificios m\u00e1s medi\u00e1ticos de Barcelona: la iglesia g\u00f3tica de Santa Maria del Mar, construida en el barrio de La Ribera entre 1329 y 1383; protagonista de un betseller de Ildefonso Falcones y de una exitosa serie de televisi\u00f3n, pero de la que se conservan pocos documentos, tras perderse en el incendio del interior de la iglesia en 1936. Vendrell ha escrito Santa Maria del Mar. Pedra a pedra (Patrimoni 2.0 edicions) un libro que publicar\u00e1 este mes en el que explica los materiales y las t\u00e9cnicas empleadas; el orden y la l\u00f3gica constructiva que se sigui\u00f3 en esta obra, as\u00ed como desmonta t\u00f3picos relacionados con este templo.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/bit.ly\/3BOFeLk\" target=\"_blank\" rel=\"noopener noreferrer\">Acceder al post<\/a><\/p>\n<hr \/>\n<h5><strong>Autores del post: <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> _ Agnieszka Stepien y Lorenzo Barn\u00f3<\/strong><\/h5>\n<h5>Y como siempre, si te gust\u00f3 el post, estar\u00eda genial que lo compartas en tus redes sociales.<\/h5>\n<h5>A su vez, si todav\u00eda no est\u00e1s suscrito a nuestra Newsletter, te animamos a hacerlo en la casilla que tienes al terminar este art\u00edculo.<\/h5>\n<p>&nbsp;<\/p>\n<p>Suscribirte a nuestro blog y recibe gratis nuestra gu\u00eda: 10 Ideas para vender m\u00e1s si eres arquitecto<\/p>\n<p>Acceder: <a href=\"http:\/\/bit.ly\/2fkkTS7\">http:\/\/bit.ly\/2fkkTS7<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Si te interesa contactar con nosotros para que te ayudemos a mejorar tu visibilidad online y, en consecuencia, mejorar tus oportunidades laborales, no dudes en escribirnos a: <a href=\"mailto:blog@stepienybarno.es\">blog@stepienybarno.es<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">Stepienybarno en TWITTER<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">@stepienybarno (+ de 16.000 seguidores)<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno?lang=es\">https:\/\/twitter.com\/stepienybarno?lang=es<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">Stepienybarno en FACEBOOK (+ de 24<u>.000 seguidores)<\/u><\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/\">https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/<\/a><\/em><\/p>\n<p><em>Acceder a nuestro GRUPO CERRADO DE FACEBOOK sobre Identidad Digital para Arquitectos:<\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/\">https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/<\/a><\/em><\/p>\n<p><em>Suscr\u00edbete a nuestro canal de YOUTUBE: <a href=\"http:\/\/bit.ly\/2A1UtAd\">http:\/\/bit.ly\/2A1UtAd<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>* <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p>Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p>A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a> y directores del blog de FUNDACI\u00d3N ARQUIA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Jos\u00e9 \u00c1ngel Monta\u00f1\u00e9s Desde: El Pa\u00eds Fotograf\u00eda: Fachada principal<\/p>\n","protected":false},"author":2,"featured_media":52194,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"audio","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[244],"tags":[9148],"series":[],"class_list":["post-52193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canal-de-arquitectura","tag-jose-angel-montanes"],"aioseo_notices":[],"episode_featured_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/02\/stepienybarno-Las-piedras-de-Santa-Maria-del-Mar-hablan-Postdeldia.jpg","episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"2YmWr76e1W\"><a href=\"https:\/\/stepienybarno.es\/blog\/2022\/03\/01\/las-piedras-de-santa-maria-del-mar-hablan\/\">Las piedras de Santa Maria del Mar hablan<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2022\/03\/01\/las-piedras-de-santa-maria-del-mar-hablan\/embed\/#?secret=2YmWr76e1W\" width=\"500\" height=\"350\" title=\"\u00abLas piedras de Santa Maria del Mar hablan\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"2YmWr76e1W\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/52193"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=52193"}],"version-history":[{"count":2,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/52193\/revisions"}],"predecessor-version":[{"id":52196,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/52193\/revisions\/52196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media\/52194"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=52193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=52193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=52193"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=52193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}