{"id":53168,"date":"2022-05-01T19:47:23","date_gmt":"2022-05-01T17:47:23","guid":{"rendered":"https:\/\/stepienybarno.es\/blog\/?p=53168"},"modified":"2022-05-01T19:49:14","modified_gmt":"2022-05-01T17:49:14","slug":"13-anos-de-stepienybarno-en-la-red","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2022\/05\/01\/13-anos-de-stepienybarno-en-la-red\/","title":{"rendered":"13 a\u00f1os de Stepienybarno en la red\u00a0"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-41550 aligncenter\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/05\/STEPIENYBARNO-logo_blanco_350.jpg\" alt=\"\" width=\"350\" height=\"350\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/05\/STEPIENYBARNO-logo_blanco_350.jpg 350w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/05\/STEPIENYBARNO-logo_blanco_350-180x180.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/05\/STEPIENYBARNO-logo_blanco_350-224x224.jpg 224w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/05\/STEPIENYBARNO-logo_blanco_350-316x316.jpg 316w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/p>\n<p>Con el paso de los a\u00f1os nos vamos haciendo veteranos de la red. Esto, de partida, es una buena se\u00f1al, pues, en estos inciertos tiempos que nos toca vivir, sobrevivir ya es un \u00e9xito.<\/p>\n<p>Si adem\u00e1s, como es nuestro caso, somos capaces de hacer lo que nos gusta y ayudar a bastantes compa\u00f1er@s arquitect@s, no podemos m\u00e1s que estar contentos.<\/p>\n<p>Si te apetece saber un poco m\u00e1s sobre nosotros, este es tu post.<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>En estos <strong>13 a\u00f1os<\/strong> hemos podido poner el foco en la\u00a0<strong>Identidad Digital y la productividad\u00a0<\/strong>dentro de nuestro mundillo arquitect\u00f3nico; lo cual, cuando arrancamos era impensable.<\/p>\n<p>Hemos tenido la suerte de decenas de cursos y escribir <a href=\"https:\/\/stepienybarno.es\/blog\/2019\/04\/10\/nuevo-libro-de-productividad-para-arquitectos-y-arquitectas\/\" target=\"_blank\" rel=\"noopener\">un libro (ver aqu\u00ed)<\/a> que que gust\u00f3 mucho.<\/p>\n<p><iframe loading=\"lazy\" title=\"Presentacio\u0301n libro  Eficiencia y productividad en Arquitectura \/ Stepienybarno\" width=\"911\" height=\"512\" src=\"https:\/\/www.youtube.com\/embed\/Pd75OS_JISY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Cuando en el 2004 montamos nuestro estudio de arquitectura !!poco pod\u00edamos imaginar la que se ven\u00eda!! De hecho, esto de estar a tantas cosas a la vez, requiere un poco de malabares.<\/p>\n<p>Los que nos vais siguiendo, veis que m\u00e1s all\u00e1 de mantener el presente blog siempre activo, estamos colaborando varios<strong>\u00a0clientes<\/strong> con los que ya llevamos mucho tiempo (Fundaci\u00f3n Arquia, Finsa, UFV,FAS\u2026).<\/p>\n<p>Tambi\u00e9n, vamos experimentando con nuevos formatos y \u00faltimamente estamos bastante fuertes en<strong>\u00a0Instagram\u00a0<\/strong>(no os perd\u00e1is los instatectura de los lunes) y en\u00a0<strong>Youtube<\/strong>\u00a0con nuestros #arquicafes y reflexiones sobre marketing e Identidad Digital.<\/p>\n<p><iframe loading=\"lazy\" title=\"Presentaci\u00f3n #ArquiCaf\u00e9\" width=\"911\" height=\"512\" src=\"https:\/\/www.youtube.com\/embed\/zpIC-eqY5rc?list=PL9KCMehqFIaiLuCrYx40SqJ4603zS946Q\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>A su vez, hemos estado detr\u00e1s de varios <strong>eventos y congresos de arquitectura<\/strong>, garantizando que tengan una buena presencia en la red.<\/p>\n<p>&nbsp;<\/p>\n<p>Son muchos frentes abiertos; pero, a d\u00eda de hoy, en el caso de que sea posible, conviene apostar por una\u00a0<strong>estrategia multicanal<\/strong>\u00a0a hora de hacer llegar el contenido.<\/p>\n<p>Con el tema de los\u00a0<strong>cursos<\/strong>, \u00faltimamente, estamos un poco parados; pero, en nuestra vida en paralelo de Haiki vamos con muchos cursos en marcha\u00a0<a href=\"https:\/\/haiki.es\/2020\/08\/taller-online-vivencial-de-eneagrama\/\">(ver aqu\u00ed)<\/a>\u00a0y !!no nos da la vida para m\u00e1s!!<\/p>\n<p>Eso s\u00ed, tenemos ganas locas de retomar nuestros cursos de marketing para arquitectos y pronto os contaremos de un nuevo formato que estamos ajustando.<\/p>\n<h4 class=\"entry-title\"><a href=\"https:\/\/stepienybarno.es\/blog\/2022\/04\/14\/curso-online-de-identidad-digital-para-arquitectos-y-arquitectas-edicion-11\/\" target=\"_blank\" rel=\"noopener\">CURSO ONLINE DE IDENTIDAD DIGITAL para ESTUDIOS DE ARQUITECTURA (EDICI\u00d3N 12)<\/a><\/h4>\n<blockquote class=\"wp-embedded-content\" data-secret=\"nuZMSq8fGv\"><p><a href=\"https:\/\/stepienybarno.es\/blog\/2022\/04\/14\/curso-online-de-identidad-digital-para-arquitectos-y-arquitectas-edicion-11\/\">CURSO ONLINE DE IDENTIDAD DIGITAL para ESTUDIOS DE ARQUITECTURA (EDICI\u00d3N 12)<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abCURSO ONLINE DE IDENTIDAD DIGITAL para ESTUDIOS DE ARQUITECTURA (EDICI\u00d3N 12)\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" src=\"https:\/\/stepienybarno.es\/blog\/2022\/04\/14\/curso-online-de-identidad-digital-para-arquitectos-y-arquitectas-edicion-11\/embed\/#?secret=8DatGmFsCr#?secret=nuZMSq8fGv\" data-secret=\"nuZMSq8fGv\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Pero, aunque todo esto es muy emocionante\u00a0 e ilusionante, no es lo mejor de estos a\u00f1os en la red. Tener bonitos proyectos y clientes estupendos, es algo por lo que podemos estar agradecidos; pero, todav\u00eda es m\u00e1s bonito ver\u00a0 l@s buen@s amig@s que hemos podido hacer en estos a\u00f1os.<\/p>\n<p>Adem\u00e1s, tenemos la suerte de tener un equipo de colaborador@s que da gusto. Gente que hace con precisi\u00f3n su tarea; pero que sobre todo son personas maravillosas.<\/p>\n<p>Mil gracias a Amparo, Loreto, Dar\u00edo, Alberto, Lola, Uxua, Susana y Marta.<\/p>\n<p>Un suerte tener esta familia de Stepienybarno siempre cerca.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-53169\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/05\/colaboradores-stepienybarno.jpeg\" alt=\"\" width=\"750\" height=\"562\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/05\/colaboradores-stepienybarno.jpeg 750w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/05\/colaboradores-stepienybarno-550x412.jpeg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/05\/colaboradores-stepienybarno-180x135.jpeg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2022\/05\/colaboradores-stepienybarno-316x237.jpeg 316w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Un abrazo para tod@s los que nos le\u00e9is de manera habitual y\u00a0 segu\u00eds de cerca esta aventura de Stepienybarno. Sin vosotr@s esto no tendr\u00eda ning\u00fan sentido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el paso de los a\u00f1os nos vamos haciendo veteranos<\/p>\n","protected":false},"author":2,"featured_media":41550,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"audio","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[4],"tags":[35],"series":[],"class_list":["post-53168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arquilectura","tag-stepienybarno"],"aioseo_notices":[],"episode_featured_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/05\/STEPIENYBARNO-logo_blanco_350.jpg","episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"TeN76cxq6F\"><a href=\"https:\/\/stepienybarno.es\/blog\/2022\/05\/01\/13-anos-de-stepienybarno-en-la-red\/\">13 a\u00f1os de Stepienybarno en la red\u00a0<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2022\/05\/01\/13-anos-de-stepienybarno-en-la-red\/embed\/#?secret=TeN76cxq6F\" width=\"500\" height=\"350\" title=\"\u00ab13 a\u00f1os de Stepienybarno en la red\u00a0\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"TeN76cxq6F\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/53168"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=53168"}],"version-history":[{"count":3,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/53168\/revisions"}],"predecessor-version":[{"id":53171,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/53168\/revisions\/53171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media\/41550"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=53168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=53168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=53168"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=53168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}