{"id":60051,"date":"2023-10-20T08:00:40","date_gmt":"2023-10-20T06:00:40","guid":{"rendered":"https:\/\/stepienybarno.es\/blog\/?p=60051"},"modified":"2023-10-18T19:20:55","modified_gmt":"2023-10-18T17:20:55","slug":"casa-morroplancho","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2023\/10\/20\/casa-morroplancho\/","title":{"rendered":"Casa Morroplancho #ProyectoDelD\u00eda"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-60059\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-1.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-1.jpg 1500w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-1-550x367.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-1-1024x683.jpg 1024w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-1-180x120.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-1-316x211.jpg 316w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/p>\n<h1><strong>Por: Capa Arquitectura<br \/>\n<\/strong><\/h1>\n<h2><strong>Desde: archdaily<\/strong><\/h2>\n<h2><strong>Fotograf\u00eda:\u00a0<\/strong>Mateo Soto<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-60060\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-2.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-2.jpg 1500w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-2-550x367.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-2-1024x683.jpg 1024w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-2-180x120.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-2-316x211.jpg 316w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-60061\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-3.jpg\" alt=\"\" width=\"1582\" height=\"890\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-3.jpg 1582w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-3-550x309.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-3-1024x576.jpg 1024w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-3-180x101.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-3-1536x864.jpg 1536w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-3-316x178.jpg 316w\" sizes=\"(max-width: 1582px) 100vw, 1582px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-60062\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-4.jpg\" alt=\"\" width=\"1416\" height=\"1000\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-4.jpg 1416w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-4-550x388.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-4-991x700.jpg 991w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-4-180x127.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-4-316x223.jpg 316w\" sizes=\"(max-width: 1416px) 100vw, 1416px\" \/><\/p>\n<p style=\"text-align: center;\">Acceder al Post <a href=\"https:\/\/www.archdaily.cl\/cl\/1008110\/casa-morroplancho-capa-arquitectura\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"\u00bfPara qu\u00e9 sirve un ARQUITECTO \/a? Por Jordi Ludevid\" width=\"911\" height=\"512\" src=\"https:\/\/www.youtube.com\/embed\/videoseries?list=PL9KCMehqFIajpdVXSncYV0J1ef6ms4zRx\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<hr \/>\n<h5><strong>Autores del post: <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> _ Agnieszka Stepien y Lorenzo Barn\u00f3<\/strong><\/h5>\n<h5>Y como siempre, si te gust\u00f3 el post, estar\u00eda genial que lo compartas en tus redes sociales.<\/h5>\n<h5>A su vez, si todav\u00eda no est\u00e1s suscrito a nuestra Newsletter, te animamos a hacerlo en la casilla que tienes al terminar este art\u00edculo.<\/h5>\n<p>&nbsp;<\/p>\n<blockquote><p>Suscribirte a nuestro blog y recibe gratis nuestra gu\u00eda: 10 Ideas para vender m\u00e1s si eres arquitecto<\/p>\n<p>Acceder: <a href=\"http:\/\/bit.ly\/2fkkTS7\">http:\/\/bit.ly\/2fkkTS7<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Si te interesa contactar con nosotros para que te ayudemos a mejorar tu visibilidad online y, en consecuencia, mejorar tus oportunidades laborales, no dudes en escribirnos a: <a href=\"mailto:blog@stepienybarno.es\">blog@stepienybarno.es<\/a><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">Stepienybarno en TWITTER<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">@stepienybarno (+ de 16.000 seguidores)<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno?lang=es\">https:\/\/twitter.com\/stepienybarno?lang=es<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">Stepienybarno en FACEBOOK (+ de 24<u>.000 seguidores)<\/u><\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/\">https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/<\/a><\/em><\/p>\n<p><em>Acceder a nuestro GRUPO CERRADO DE FACEBOOK sobre Identidad Digital para Arquitectos:<\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/\">https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/<\/a><\/em><\/p>\n<p><em>Suscr\u00edbete a nuestro canal de YOUTUBE: <a href=\"http:\/\/bit.ly\/2A1UtAd\">http:\/\/bit.ly\/2A1UtAd<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>* <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p>Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p>A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Capa Arquitectura Desde: archdaily Fotograf\u00eda:\u00a0Mateo Soto Acceder al Post<\/p>\n","protected":false},"author":2,"featured_media":60059,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"audio","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[3197,244],"tags":[9995],"series":[],"class_list":["post-60051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectodeldia","category-canal-de-arquitectura","tag-capa-arquitectura"],"aioseo_notices":[],"episode_featured_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2023\/10\/stepienybarno-Casa-Morroplancho-ProyectoDelDia-1.jpg","episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"0vo1xrZfpS\"><a href=\"https:\/\/stepienybarno.es\/blog\/2023\/10\/20\/casa-morroplancho\/\">Casa Morroplancho #ProyectoDelD\u00eda<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2023\/10\/20\/casa-morroplancho\/embed\/#?secret=0vo1xrZfpS\" width=\"500\" height=\"350\" title=\"\u00abCasa Morroplancho #ProyectoDelD\u00eda\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"0vo1xrZfpS\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/60051"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=60051"}],"version-history":[{"count":3,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/60051\/revisions"}],"predecessor-version":[{"id":60064,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/60051\/revisions\/60064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media\/60059"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=60051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=60051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=60051"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=60051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}