{"id":61296,"date":"2024-01-26T08:01:45","date_gmt":"2024-01-26T06:01:45","guid":{"rendered":"https:\/\/stepienybarno.es\/blog\/?p=61296"},"modified":"2024-01-22T20:35:17","modified_gmt":"2024-01-22T18:35:17","slug":"las-lecciones-del-oficio-de-la-creatividad-a-la-solvencia-del-hecho-construido-blancafort-reus","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2024\/01\/26\/las-lecciones-del-oficio-de-la-creatividad-a-la-solvencia-del-hecho-construido-blancafort-reus\/","title":{"rendered":"Las lecciones del oficio. De la creatividad a la solvencia del hecho construido"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-61297\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2024\/01\/stepienybarno-Las-lecciones-del-oficio.-De-la-creatividad-a-la-solvencia-del-hecho-construido-Postdeldia.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2024\/01\/stepienybarno-Las-lecciones-del-oficio.-De-la-creatividad-a-la-solvencia-del-hecho-construido-Postdeldia.jpg 750w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2024\/01\/stepienybarno-Las-lecciones-del-oficio.-De-la-creatividad-a-la-solvencia-del-hecho-construido-Postdeldia-550x367.jpg 550w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2024\/01\/stepienybarno-Las-lecciones-del-oficio.-De-la-creatividad-a-la-solvencia-del-hecho-construido-Postdeldia-180x120.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2024\/01\/stepienybarno-Las-lecciones-del-oficio.-De-la-creatividad-a-la-solvencia-del-hecho-construido-Postdeldia-316x211.jpg 316w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<h1><strong>Por: Blancafort &#8211; Reus<br \/>\n<\/strong><\/h1>\n<h2>Desde: <strong>madera y construcci\u00f3n<\/strong><\/h2>\n<h2>Fotograf\u00eda: Workshop sur le fleuve Bouregreg pour la Biennale d\u2019Architecture Agora Rabat-Sal\u00e9. Imagen: Fabien Salhen. H.M.O.N.P<\/h2>\n<p>\u201cLa magia de lo verdadero y de lo real\u201d Zumthor. Atm\u00f3sferas<\/p>\n<p>En este texto queremos desarrollar dos ideas que consideramos complementarias y que, de alguna manera, orbitan el universo de maestros de la arquitectura contempor\u00e1nea como Peter Zumthor, iniciado en el mundo de la arquitectura a trav\u00e9s de la ebanister\u00eda o se aproximan a la apuesta del learning by doing desplegada en Taliesin por Frank Lloyd Wright.<\/p>\n<p>La primera de estas ideas tiene que ver con las lecciones que nos da la construcci\u00f3n f\u00edsica de un proyecto, y la segunda se relaciona con la convicci\u00f3n de que la arquitectura, adem\u00e1s de ser concepto espacial, es tambi\u00e9n entidad construida y como tal, es transmisora de todas aquellas sensaciones y efectos psicol\u00f3gicos que provocan la solvencia material.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/maderayconstruccion.com\/las-lecciones-del-oficio-de-la-creatividad-a-la-solvencia-del-hecho-construido\/\" target=\"_blank\" rel=\"noopener\">Acceder al post<\/a><\/p>\n<hr \/>\n<h5><strong>Autores del post: <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> _ Agnieszka Stepien y Lorenzo Barn\u00f3<\/strong><\/h5>\n<h5>Y como siempre, si te gust\u00f3 el post, estar\u00eda genial que lo compartas en tus redes sociales.<\/h5>\n<h5>A su vez, si todav\u00eda no est\u00e1s suscrito a nuestra Newsletter, te animamos a hacerlo en la casilla que tienes al terminar este art\u00edculo.<\/h5>\n<p>&nbsp;<\/p>\n<p>Suscribirte a nuestro blog y recibe gratis nuestra gu\u00eda: 10 Ideas para vender m\u00e1s si eres arquitecto<\/p>\n<p>Acceder: <a href=\"http:\/\/bit.ly\/2fkkTS7\">http:\/\/bit.ly\/2fkkTS7<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Si te interesa contactar con nosotros para que te ayudemos a mejorar tu visibilidad online y, en consecuencia, mejorar tus oportunidades laborales, no dudes en escribirnos a: <a href=\"mailto:blog@stepienybarno.es\">blog@stepienybarno.es<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">Stepienybarno en TWITTER<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno\">@stepienybarno (+ de 16.000 seguidores)<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/twitter.com\/stepienybarno?lang=es\">https:\/\/twitter.com\/stepienybarno?lang=es<\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">Stepienybarno en FACEBOOK (+ de 24<u>.000 seguidores)<\/u><\/a><\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/\">https:\/\/www.facebook.com\/StepienyBarnoArquitecturaeIdentidadDigital\/<\/a><\/em><\/p>\n<p><em>Acceder a nuestro GRUPO CERRADO DE FACEBOOK sobre Identidad Digital para Arquitectos:<\/em><\/p>\n<p><em><a href=\"https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/\">https:\/\/www.facebook.com\/groups\/IdentidadDigitalParaArquitectos\/<\/a><\/em><\/p>\n<p><em>Suscr\u00edbete a nuestro canal de YOUTUBE: <a href=\"http:\/\/bit.ly\/2A1UtAd\">http:\/\/bit.ly\/2A1UtAd<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>* <a href=\"https:\/\/stepienybarno.es\/blog\/2011\/09\/04\/las-fortalezas-del-arquitecto\/\">Stepienybarno<\/a> est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p>Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p>A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Blancafort &#8211; Reus Desde: madera y construcci\u00f3n Fotograf\u00eda: Workshop<\/p>\n","protected":false},"author":2,"featured_media":61297,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"audio","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[244],"tags":[2298],"series":[],"class_list":["post-61296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canal-de-arquitectura","tag-blancafort-reus"],"aioseo_notices":[],"episode_featured_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2024\/01\/stepienybarno-Las-lecciones-del-oficio.-De-la-creatividad-a-la-solvencia-del-hecho-construido-Postdeldia.jpg","episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"4Ftd8ayO1g\"><a href=\"https:\/\/stepienybarno.es\/blog\/2024\/01\/26\/las-lecciones-del-oficio-de-la-creatividad-a-la-solvencia-del-hecho-construido-blancafort-reus\/\">Las lecciones del oficio. De la creatividad a la solvencia del hecho construido<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2024\/01\/26\/las-lecciones-del-oficio-de-la-creatividad-a-la-solvencia-del-hecho-construido-blancafort-reus\/embed\/#?secret=4Ftd8ayO1g\" width=\"500\" height=\"350\" title=\"\u00abLas lecciones del oficio. De la creatividad a la solvencia del hecho construido\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"4Ftd8ayO1g\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/61296"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=61296"}],"version-history":[{"count":1,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/61296\/revisions"}],"predecessor-version":[{"id":61298,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/61296\/revisions\/61298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media\/61297"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=61296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=61296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=61296"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=61296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}