{"id":6142,"date":"2012-09-03T10:45:49","date_gmt":"2012-09-03T08:45:49","guid":{"rendered":"https:\/\/www.stepienybarno.es\/blog\/?p=6142"},"modified":"2012-09-03T13:32:16","modified_gmt":"2012-09-03T11:32:16","slug":"el-complejo-del-museo-de-la-evolucion-humana-de-juan-navarro-baldeweg","status":"publish","type":"post","link":"https:\/\/stepienybarno.es\/blog\/2012\/09\/03\/el-complejo-del-museo-de-la-evolucion-humana-de-juan-navarro-baldeweg\/","title":{"rendered":"EL COMPLEJO DEL MUSEO DE LA  EVOLUCI\u00d3N HUMANA DE JUAN NAVARRO BALDEWEG"},"content":{"rendered":"<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6143\" title=\"0. MEH museo burgos evolucion _ juan navarro baldeberg _boceto  _ step\u00ecenybarno 350\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/0.-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_boceto-_-step\u00ecenybarno-350-.jpg\" alt=\"0. MEH museo burgos evolucion _ juan navarro baldeberg _boceto  _ step\u00ecenybarno 350\" width=\"350\" height=\"203\" srcset=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/0.-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_boceto-_-step\u00ecenybarno-350-.jpg 350w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/0.-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_boceto-_-step\u00ecenybarno-350--180x104.jpg 180w, https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/0.-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_boceto-_-step\u00ecenybarno-350--316x183.jpg 316w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/p>\n<p>Hace unos d\u00edas y, siendo sinceros, atra\u00eddos m\u00e1s por la exposici\u00f3n que por el propio edificio, pudimos visitar el Museo de la Evoluci\u00f3n Humana (MEH) de Burgos, obra del estudio del arquitecto y pintor Juan Navarro Baldeweg.<\/p>\n<p>Por ello, la entrada de hoy va sobre nuestra experiencia en la visita y, poniendo por delante que no es una cr\u00edtica de arquitectura al proyecto, nos apetec\u00eda compartir con tod@s vosotr@s algunas de las sensaciones que nos trajimos de vuelta a casa.<\/p>\n<p>Por lo tanto, si os apeste acompa\u00f1arnos en el recuerdo de este viaje, no ten\u00e9is m\u00e1s que seguir leyendo.<\/p>\n<p><!--more--><\/p>\n<p>Visitar un museo, para un arquitecto, siempre es una experiencia complicada y, en muchos casos, apasionante. Si realmente te interesa la exposici\u00f3n, estar presente en la misma sin \u201cdistraerte\u201d con la arquitectura no es nada f\u00e1cil. Igualmente, la mayor\u00eda de nuestras visitas para ver museos, acaban \u201ccontamin\u00e1ndose\u201d con las exposiciones que albergan.<\/p>\n<p>De hecho, <strong>la palabra \u201cver\u201d seguramente no es la m\u00e1s adecuada, pues la experiencia de visitar una buena obra de arquitectura lo que te hace es poder habitarla, <\/strong>aunque sea por unas horas.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6144\" title=\"1. MEH museo burgos evolucion _ juan navarro baldeberg _ planta _ step\u00ecenybarno 500\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/1.-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-planta-_-step\u00ecenybarno-500--350x153.jpg\" alt=\"1. MEH museo burgos evolucion _ juan navarro baldeberg _ planta _ step\u00ecenybarno 500\" width=\"350\" height=\"153\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Planta de situaci\u00f3n<\/span><\/p>\n<p>A su vez, antes de entrar en materia, nos parece\u00a0 importante rese\u00f1ar que la arquitectura de <em>Juan Navarro Baldeweg,<\/em> en general, nos parece de primer\u00edsimo nivel.<\/p>\n<p>Dicho esto, nuestra llegada al museo se produjo sin mucho conocimiento de lo que all\u00e1 nos \u00edbamos a encontrar y la primera impresi\u00f3n result\u00f3 un tanto ambigua. Tambi\u00e9n es cierto que, nuestro entusiasmo por el proyecto fue aumentando conforme pas\u00e1bamos del exterior al interior.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6145\" title=\"2. MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/2.-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500--350x220.jpg\" alt=\"2. MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" width=\"350\" height=\"220\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Fotograf\u00eda: Stepienybarno<\/span><\/p>\n<p align=\"center\">\n<p>El edificio, inaugurado hace un par de a\u00f1os como consecuencia de un concurso celebrado en el a\u00f1o 2000, se compone de tres grandes vol\u00famenes que alojan usos muy variados: Centro Nacional de Investigaci\u00f3n sobre la Evoluci\u00f3n Humana (CENIEH), Palacio de congresos, y, el que m\u00e1s nos interesaba, la exposici\u00f3n arqueol\u00f3gica dirigida por los equipos paleontol\u00f3gicos de la <em>Sierra de Atapuerca <\/em>(<em>Juan Luis Arsuaga, Jos\u00e9 Mar\u00eda Berm\u00fadez de Castro y Eudald Carbonell<\/em>).<\/p>\n<p>Los tres vol\u00famenes \u00a0quedan recubiertos por \u00a0una piel de vidrio que, con distintos matices, da frente a la ciudad. Tambi\u00e9n es cierto que, nuestra poca devoci\u00f3n por este tipo de fachadas, no ayud\u00f3 a comenzar con buen pie nuestro encuentro con el museo.<\/p>\n<p>Aun as\u00ed, creemos que hay un esfuerzo evidente por realizar una obra que sin dejar de ser, en cierta forma, ic\u00f3nica, sea respetuosa con el entorno en el que se inserta. Por lo que pudimos deducir de conversaciones con alg\u00fan burgal\u00e9s, la obra ha sido bastante bien aceptada en la ciudad, aunque m\u00e1s de uno se quej\u00f3 de que no resultaba tan impactante como el Guggenheim de Bilbao. Pero claro, en este sentido <strong>es de agradecer la contenci\u00f3n formal del proyecto, pues el efecto Bilbao funcion\u00f3 en unas condiciones muy determinadas y sus replicas, son, en el mejor de los casos, pan para hoy hambre para ma\u00f1ana.<\/strong> Citando a <em>Juan Navarro Baldeweg<\/em>, \u201cEl<em> Guggenheim<\/em> de <em>Frank Gehry <\/em>es muy formal, de efectos, y este edificio es m\u00e1s de relaciones\u201d. Sin duda, mucho mejor una arquitectura que sue\u00f1a con hacer ciudad en vez de imponerse al resto de la ciudad.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6146\" title=\"3.1 MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/3.1-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500--350x206.jpg\" alt=\"3.1 MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" width=\"350\" height=\"206\" \/><\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6147\" title=\"3.2  MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/3.2-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500-350x230.jpg\" alt=\"3.2  MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" width=\"350\" height=\"230\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Fotograf\u00eda: Stepienybarno<\/span><\/p>\n<p>El proyecto que gan\u00f3 el concurso estaba constituido por un solo bloque en el que reinaba una mayor continuidad. A\u00fan as\u00ed, la actual ruptura en tres vol\u00famenes creemos que tiene su inter\u00e9s y, a su vez, lo hace muy f\u00e1cil de usar. Pero, no parece que\u00a0 nuevas grietas terminen de explotar todo su aparente potencial. Desde la distancia, nos las imagin\u00e1bamos como canales de actividad y nexos de uni\u00f3n del\u00a0 brillante preludio vegetal con una parte m\u00e1s aguerrida y desconocida de la ciudad. La realidad, es que resultan pasos muy poco transitados, a los que las tremendas estructuras en forma de aspas pintadas de color rojo (con eminente carga simb\u00f3lica en su elecci\u00f3n ya que, con ello, se pretende evocar el ocre de la propia sierra), quiz\u00e1s no le ayuden a que sean espacios un poquito m\u00e1s acogedores.<\/p>\n<p>La llegada principal\u00a0 se produce por un agradable paseo que fluye paralelo al hist\u00f3rico r\u00edo <em>Alarz\u00f3n<\/em>, con una vegetaci\u00f3n muy cuidada, diversas esculturas y una curiosa fuente que hace las delicias de los m\u00e1s peque\u00f1os. Estas aguas fluviales que, curiosamente, llegan desde la propia sierra de<em> Atapuerca<\/em> (uno de los <strong>p<\/strong><strong>rincipales yacimientos paleontol\u00f3gicos del mundo<\/strong>), son el perfecto pre\u00e1mbulo a la experiencia del museo. Desde ah\u00ed, se accede a una colina artificial, previa al edificio, cuya vegetaci\u00f3n es una traslaci\u00f3n literal de parte de lo \u00a0que en su d\u00eda pudo haber sido la propia sierra. Con este mecanismo, <strong>se consigue una adecuada continuidad entre el exterior y el interior. Estando fuera ya se puede intuir que algo est\u00e1 pasando y cuando, finalmente, est\u00e1s dentro no pierdes referencias con el exterior<\/strong>, aunque sea de manera m\u00e1s conceptual, como explicaremos m\u00e1s adelante.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6148\" title=\"4. MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/4.-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500--350x233.jpg\" alt=\"4. MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" width=\"350\" height=\"233\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Fotograf\u00eda: Stepienybarno<\/span><\/p>\n<p align=\"left\">\n<p align=\"left\">El acceso definitivo al edificio, se produce desde una cota (+5mts) lo suficientemente elevada como para que se entable un nuevo di\u00e1logo visual con el gran hito de la ciudad: su catedral. Seg\u00fan <em>Navarro Baldeweg<\/em>, \u201chay una intenci\u00f3n clara para que la marquesina parezca un dedo \u00edndice que se\u00f1ale la Catedral\u201d.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6149\" title=\"5  MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/5-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500--350x223.jpg\" alt=\"5  MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" width=\"350\" height=\"223\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Fotograf\u00eda: Stepienybarno<\/span><\/p>\n<p>El resto de las fachadas del edificio, tampoco se nos hac\u00edan f\u00e1ciles de digerir. En uno de los laterales aparecen una serie de paneles que, creemos, quieren recrear una especie de lluvia \u00e1cida, pero m\u00e1s all\u00e1 de estas intenciones, se nos hac\u00eda un tanto agresiva. A su vez, <strong>toda la parte posterior, termina siendo, quiz\u00e1s, demasiado trasera, quedando la otra fachada lateral presa de un gran esfuerzo formal, que no parece terminar de cuajar. <\/strong><\/p>\n<p>A pesar de todo ello, el edificio mantiene el tipo, y es de agradecer el extremo cuidado en su ejecuci\u00f3n y los esfuerzos del proyecto por no perderse en el detalle y que cada l\u00ednea (literal) est\u00e1 pensada y tenga su intenci\u00f3n.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6150\" title=\"6.MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/6.MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500--350x233.jpg\" alt=\"6.MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" width=\"350\" height=\"233\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Fotograf\u00eda: Stepienybarno<\/span><\/p>\n<p>Pero, vamos acerc\u00e1ndonos al edificio que ya estamos dando demasiados rodeos! La llegada al museo, ahora s\u00ed, se produce por una marquesina de unos 5 metros de vuelo que ayuda a acotar el espacio (aunque se nos hizo un tanto alta) y mitigar el casi siempre brusco cambio entre exterior\u00a0 e interior. Se agradece, nuevamente, este esfuerzo por la transici\u00f3n pues la entrada al interior se realiza desde una descompresi\u00f3n total del espacio.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6151\" title=\"7. MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/7.-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500--350x241.jpg\" alt=\"7. MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" width=\"350\" height=\"241\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Fotograf\u00eda: Stepienybarno<\/span><\/p>\n<p>De un solo vistazo, se puede contemplar un gran y di\u00e1fano espacio, de 30 metros de altura, con varias bandejas situadas al fondo y en donde se alojan las exposiciones permanentes.<\/p>\n<p>La luminosidad que reina en este interior se consigue gracias a \u00a0la doble piel de vidrio de las fachadas y el control lum\u00ednico de las lamas de la, tambi\u00e9n acristalada, cubierta. <strong>La sensaci\u00f3n de paz y serenidad era estupenda, aunque no se hac\u00eda dif\u00edcil sospechar el alto peaje energ\u00e9tico que se debe pagar para conseguirlo.<\/strong> Aun as\u00ed, seguramente esta opci\u00f3n tecnol\u00f3gica es la menos mala de las posibles para crear \u00a0este espacio.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6152\" title=\"068DQ20110323D0017.jpg\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/8.-thomas-mayer_-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500--350x233.jpg\" alt=\"068DQ20110323D0017.jpg\" width=\"350\" height=\"233\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Vista desde la cota de acceso\u00a0 (planta 0).<\/span><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Fotograf\u00eda: Thomas Mayer<\/span><\/p>\n<p>Desde ah\u00ed, tambi\u00e9n se puede intuir \u00a0el \u201cviaje\u201d que se ha<em> <\/em>dise\u00f1ado para el visitante. A su vez, aquellas aspas estructurales, que cit\u00e1bamos l\u00edneas m\u00e1s arriba, son las responsables de que se pueda salvar una luz de 60 metros. Esta apuesta estructural ayuda, realmente, a recrear el ambiente natural de la <em>Sierra de Atapuerca <\/em>y \u00a0es uno de las grandes apuestas del proyecto. \u00abDesde el primer momento tuvimos claro que \u00e9ste deb\u00eda ser el objetivo de nuestro proyecto: <strong>lograr poner en relaci\u00f3n arquitectura y naturaleza<\/strong>. Finalmente el<em> MEH <\/em>puede verse como met\u00e1fora de la vida en general y de nuestra relaci\u00f3n con la vida y tambi\u00e9n con el sol\u00bb, seg\u00fan, nuevamente, palabras del arquitecto.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6153\" title=\"9. MEH museo burgos evolucion _ juan navarro baldeberg axono metrica _ step\u00ecenybarno 500\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/9.-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-axono-metrica-_-step\u00ecenybarno-500--297x349.jpg\" alt=\"9. MEH museo burgos evolucion _ juan navarro baldeberg axono metrica _ step\u00ecenybarno 500\" width=\"297\" height=\"349\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Axonometr\u00eda del museo.<\/span><\/p>\n<p>Conviene destacar que, en todo el museo se evita el \u00e1ngulo recto y casi todo se \u201c<em>tuerce<\/em>\u201d hacia las coordenadas de la Catedral, desde el pavimento hasta los paneles informativos.<\/p>\n<p>Como decimos, para nosotros la experiencia fue una aut\u00e9ntica promenade; un primer descenso (planta -1) nos hizo llegar, por un lado, a las exposiciones\u00a0 temporales y, por otro, pudimos entrar \u00a0en la parte dedicada al yacimiento de <em>Atapuerca<\/em>. En este \u00e1mbito destacan cuatro cajas ligeramente inclinadas, a modo de \u201ccuevas\u201d, donde lo sonoro y la temperatura ayudan a meterte en situaci\u00f3n. All\u00e1, se exponen los restos arqueol\u00f3gicos que te trasladan a un mundo de encuentros entre <em>Neardentales<\/em> y <em>Homo Sapiens Sapiens<\/em>, la aparici\u00f3n del <em>Homo Antecessor<\/em>, el bifaz del <em>Excalibur <\/em>o la cadera de <em>Elvis.<\/em> Aunque el material\u00a0 expuesto es de primer nivel y los paneles informativos est\u00e1n m\u00e1s que bien, echamos de menos m\u00e1s restos f\u00f3siles originales. A todo ello, hay que sumar que al ser la parte m\u00e1s atractiva del museo y la que primero se visita, te provoca un poco de agobio y es complicado estar concentrado en la propia exposici\u00f3n. Por ello, es m\u00e1s que recomendable volver a pasarse por esta zona cuando se desatasca el tr\u00e1fico.<\/p>\n<p>Estos habit\u00e1culos est\u00e1n separados entre s\u00ed por generosos pasillos que quieren evocar la irrupci\u00f3n del ferrocarril en la propia sierra, a finales del siglo XIX. Su llegada se realiz\u00f3 mediante largas y profundas trincheras excavadas en la tierra. De esta forma, los trabajadores que realizaban las excavaciones se fueron encontrando con zonas de arcilla roja y cuevas que hab\u00edan quedado sepultadas por la sedimentaci\u00f3n, conservando en su interior: el gran tesoro arqueol\u00f3gico de la Sierra de Atapuerca. Hoy, <strong>el museo se nutre de estas <a href=\"http:\/\/www.youtube.com\/watch?v=ism-ZIAK0v0\">joyas prehist\u00f3ricas<\/a> y, a su vez, intenta trasladar los acontecimientos del entorno natural a su interior como si de una met\u00e1fora de la vida y del paso del tiempo se tratase.<\/strong><\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6161\" title=\"068DQ20110323D0019.jpg\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/10.-thomas-mayer_-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500--350x233.jpg\" alt=\"068DQ20110323D0019.jpg\" width=\"350\" height=\"233\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Vista del espacio central desde la cota de acceso\u00a0 (planta 0).<\/span><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Fotograf\u00eda: Thomas Mayer<\/span><\/p>\n<p align=\"left\">\n<p align=\"left\">Desde esta primera inmersi\u00f3n se accede a un nivel de cota de acceso (planta 0) que te permite contemplar los techos de estas cuatro cajas-cuevas. En ellos, <strong>se recrean cuatro ambientes naturales de la propia sierra que completan esa otra recreaci\u00f3n de la colina de acceso al museo que cit\u00e1bamos l\u00edneas arriba. <\/strong><\/p>\n<p align=\"left\">En este nivel nos encontramos dos exposiciones; una primera, obra de Elisabeth Dayn\u00e8s, que est\u00e1 dedicada a una estupenda recreaci\u00f3n, de car\u00e1cter naturalista a escala 1:1, de varios de los momentos m\u00e1s importantes de la evoluci\u00f3n de nuestra especie y otra que quiere recrear un cerebro humano y, la verdad, no terminamos de entender muy bien.<\/p>\n<p align=\"left\">\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6155\" title=\"068DQ20110323D0021.jpg\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/11.-thomas-mayer_-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500-1-350x233.jpg\" alt=\"068DQ20110323D0021.jpg\" width=\"350\" height=\"233\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Vista del espacio central desde la planta 1.<\/span><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Fotograf\u00eda: Thomas Mayer<\/span><\/p>\n<p align=\"left\"><span style=\"color: #888888;\"> <\/span><\/p>\n<p align=\"left\">Si continuamos el viaje y llegamos al siguiente nivel, nos encontramos con el fuego como protagonista. Aqu\u00ed, coge excesivo protagonismo un habit\u00e1culo esf\u00e9rico en el que se proyectan una serie de im\u00e1genes en torno al fuego. Quiz\u00e1s, el proyecto museogr\u00e1fico no est\u00e9, en ocasiones, a la altura de las circunstancias; eso s\u00ed, los gu\u00edas del museo o, por lo menos, al gu\u00eda del museo que nos atendi\u00f3, adem\u00e1s de ser un estupendo comunicador, se le notaba que sus palabras sal\u00edan del conocimiento integrado y no de la lectura de unos pocos libros sobre el tema en cuesti\u00f3n.<\/p>\n<p align=\"left\">\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6156\" title=\"12. MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/12.-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500--350x233.jpg\" alt=\"12. MEH museo burgos evolucion _ juan navarro baldeberg _ step\u00ecenybarno 500\" width=\"350\" height=\"233\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Fotograf\u00eda: Stepienybarno<\/span><\/p>\n<p align=\"left\">\n<p align=\"left\">Y, ya, en el \u00faltimo nivel, se encuentra una sencilla pero complet\u00edsima librer\u00eda con otros servicios adyacentes. Desde ah\u00ed, <strong>se puede contemplar ese gran espacio que quiere hacer un intenso homenaje a las condiciones naturales del entorno de los yacimientos. <\/strong><\/p>\n<p align=\"left\"><em>Juan Navarro Baldeweg<\/em>, se refiere a este espacio afirmando que, \u201ces como un gran invernadero en el cual el sustrato, lo geol\u00f3gico, estuviera presente, pues la recreaci\u00f3n debajo de las trincheras&#8230; Sigues el recorrido, entras en el Museo subiendo una rampa, ves las trincheras y bajas. Y ese sentimiento de estar bajo tierra tienes que notarlo tambi\u00e9n. Y ah\u00ed se reproducen los contenidos que pertenecen al subsuelo, al sustrato.\u201d<\/p>\n<p>As\u00ed, la luz natural y la dimensi\u00f3n del espacio cogen su merecido protagonismo, siendo su\u00a0 tama\u00f1o infinitamente mayor de lo que se pudiera esperar antes de haber entrado en el edificio. Aunque, puestos a pedir, se nos ocurre que no hubiera estado nada mal, poder llegar a una cubierta transitable desde donde poder disfrutar de una nueva postal de la ciudad.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6157\" title=\"068DQ20110323D0022.jpg\" src=\"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2012\/09\/13.-thomas-mayer_-MEH-museo-burgos-evolucion-_-juan-navarro-baldeberg-_-step\u00ecenybarno-500--350x233.jpg\" alt=\"068DQ20110323D0022.jpg\" width=\"350\" height=\"233\" \/><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Vista del espacio central desde la planta 3.<\/span><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Fotograf\u00eda: Thomas Mayer<\/span><\/p>\n<p>La visita a la exposici\u00f3n y al edificio, a pesar de los \u201cperos\u201d que hemos mencionado, nos result\u00f3 m\u00e1s que gratificante. Creemos que, es muy de agradecer una arquitectura que sabe encontrar el equilibrio entre lo ic\u00f3nico y el \u201canonimato\u201d y, sobre todo, entre una parte conceptual y otra m\u00e1s emocional. Un fluir de estados de \u00e1nimos se despliegan en la visita al museo y eso es ya una garant\u00eda de que la arquitectura est\u00e1 presente y ha sabido encontrar su sitio.<\/p>\n<p>En fin, de esta forma termin\u00f3 nuestro paseo por el \u00a0museo y emprendimos nuestra marcha (salt\u00e1ndonos el espantoso puesto de regalos de la salida) cargados de unos cuantos libros que nos seguir\u00e1n deleitando con este apasionante periodo de nuestra historia. Con ellos podremos seguir so\u00f1ando y evocando tiempos en los que la fecundidad, fertilidad y sexualidad ocupaban un lugar preferente en el d\u00eda a d\u00eda de esta m\u00e1s que interesante sociedad matriarcal.<\/p>\n<p>Todo un mundo de misterio y epopeyas que nos conecta directamente con nuestros or\u00edgenes y que nos hacen escapar, aunque sea por un instante, de esta sociedad de la raz\u00f3n y de lo inmediato que se ha alejado tanto de los misterios de la naturaleza y el respeto hacia nuestros semejantes.<\/p>\n<p>Texto: Stepienybarno<\/p>\n<p>Fotograf\u00edas: seg\u00fan referencia.<\/p>\n<p>* Este art\u00edculo ha sido escrito con car\u00e1cter divulgativo y sin ning\u00fan tipo de \u00e1nimo de lucro. As\u00ed que, si te apetece <strong>compartirlo<\/strong> en cualquier otro medio, estaremos encantados de que lo hagas siempre y cuando cites el lugar donde lo has encontrado.<\/p>\n<p>Autores de la entrada: <a href=\"http:\/\/www.facebook.com\/col.prudant#!\/StepienybarnoCANAL\">Stepienybarno<\/a><\/p>\n<p><a href=\"http:\/\/www.linkedin.com\/company\/stepienybarno\">STEPIENYBARNO EN LINKEDIN<\/a><\/p>\n<p><a href=\"http:\/\/twitter.com\/stepienybarno\/stepienybarno\">STEPIENYBARNO EN TWITTER<\/a><\/p>\n<p align=\"left\"><a href=\"https:\/\/www.facebook.com\/pages\/BLOG-DE-STEPIENYBARNO\/78001079029\">STEPIENYBARNO EN FACEBOOK<\/a><\/p>\n<p>* Stepienybarno est\u00e1 formado por Agnieszka Stepien y Lorenzo Barn\u00f3 y desde mayo del 2009 estamos en la red con\u00a0 la presente publicaci\u00f3n digital (Blog) de arquitectura.<\/p>\n<p>Nuestra actividad se sustenta en tres pilares b\u00e1sicos: la investigaci\u00f3n, la publicaci\u00f3n y la redacci\u00f3n de proyectos de arquitectura.<\/p>\n<p>A su vez, somos socios cofundadores de <a href=\"http:\/\/sinergiasostenible.org\/\">SINERGIA SOSTENIBLE<\/a> y redactores de <a href=\"http:\/\/www.laciudadviva.org\/blogs\/?author=45\">LA CIUDAD VIVA<\/a>.<\/p>\n<p align=\"left\">* Los editores de esta publicaci\u00f3n digital no nos hacemos cargo de de los comentarios y\u00a0 conceptos vertidos en los textos firmados por otras personas, siendo \u00e9stos de responsabilidad exclusiva de sus autores.<\/p>\n<p>* Tu comentario pudiera ser moderado, por lo tanto, aunque aparezca inmediatamente al ser publicado en la entrada, los editores de esta publicaci\u00f3n digital nos reservamos el derecho tanto de editarlo (si fuera necesario, para hacerlo m\u00e1s legible) como de eliminarlo en el caso de que se usen expresiones incorrectas (descalificaciones, palabras malsonantes\u2026). A su vez, si quieres comentar desde el anonimato puedes hacerlo, aunque, nosotros personalmente, agradecemos que tod@s nos podamos identificar.<\/p>\n","protected":false},"excerpt":{"rendered":"\n<p>Hace unos d\u00edas y, siendo sinceros, atra\u00eddos m\u00e1s por la exposici\u00f3n que por el propio edificio, pudimos visitar el Museo de la Evoluci\u00f3n Humana (MEH) de Burgos, obra del estudio del arquitecto y pintor Juan Navarro Baldeweg.<\/p>\n<p>Por ello, la entrada de hoy va sobre nuestra experiencia en la visita y, poniendo por delante que no es una cr\u00edtica de arquitectura al proyecto, nos apetec\u00eda compartir con tod@s vosotr@s algunas de las sensaciones que nos trajimos de vuelta a casa.<\/p>\n<p>Por lo tanto, si os apeste acompa\u00f1arnos en el recuerdo de este viaje, no ten\u00e9is m\u00e1s que seguir leyendo.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[34,4],"tags":[4274,9,1000,1911,1910],"series":[],"class_list":["post-6142","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-arquilectura","tag-actualidad","tag-arquitectura","tag-juan-navarro-baldeweg","tag-meh","tag-museo-de-la-evolucion-humana"],"aioseo_notices":[],"episode_featured_image":false,"episode_player_image":"https:\/\/stepienybarno.es\/blog\/wp-content\/uploads\/2020\/11\/stepienybarno-podcast-scaled.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/stepienybarno.es\/blog\/feed\/podcast\/podcast-de-stepienybarno","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"DuCQ3xmaBt\"><a href=\"https:\/\/stepienybarno.es\/blog\/2012\/09\/03\/el-complejo-del-museo-de-la-evolucion-humana-de-juan-navarro-baldeweg\/\">EL COMPLEJO DEL MUSEO DE LA  EVOLUCI\u00d3N HUMANA DE JUAN NAVARRO BALDEWEG<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/stepienybarno.es\/blog\/2012\/09\/03\/el-complejo-del-museo-de-la-evolucion-humana-de-juan-navarro-baldeweg\/embed\/#?secret=DuCQ3xmaBt\" width=\"500\" height=\"350\" title=\"\u00abEL COMPLEJO DEL MUSEO DE LA  EVOLUCI\u00d3N HUMANA DE JUAN NAVARRO BALDEWEG\u00bb \u2014 Blog de STEPIEN Y BARNO - publicaci\u00f3n digital sobre arquitectura\" data-secret=\"DuCQ3xmaBt\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/6142"}],"collection":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/comments?post=6142"}],"version-history":[{"count":6,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/6142\/revisions"}],"predecessor-version":[{"id":6159,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/posts\/6142\/revisions\/6159"}],"wp:attachment":[{"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/media?parent=6142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/categories?post=6142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/tags?post=6142"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/stepienybarno.es\/blog\/wp-json\/wp\/v2\/series?post=6142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}